{"id":19017348,"date":"2026-09-01T20:49:10","date_gmt":"2026-09-01T18:49:10","guid":{"rendered":"https:\/\/migflug.com\/afterburner\/altius-700-black-hawk-rocket-launch-anduril-project-convergence-2026\/"},"modified":"2026-09-02T08:46:21","modified_gmt":"2026-09-02T06:46:21","slug":"altius-700-black-hawk-raketenstart-anduril-projekt-konvergenz-2026","status":"publish","type":"post","link":"https:\/\/migflug.com\/afterburner\/de\/altius-700-black-hawk-rocket-launch-anduril-project-convergence-2026\/","title":{"rendered":"Altius-700: Eine Black-Hawk-Rakete startet Andurils Drohne"},"content":{"rendered":"<style>.et_pb_title_container h1.entry-title { padding-top: 40px !important; }<\/style><p>Die US-Armee hat ihren bew\u00e4hrten Truppentransporter in eine Startplattform f\u00fcr autonome Kampfdrohnen umgewandelt. Aufnahmen, die von Anduril am 31. August ver\u00f6ffentlicht wurden, zeigen, wie ein H-60M Black Hawk eine Altius-700 von einem externen Pylon aus startet. Die Drohne rast \u00fcber die Mojave-W\u00fcste, bevor eine Formation von ihnen selbstst\u00e4ndig ein Ziel verfolgt.<\/p>\r\n<p>Der Black Hawk ist kein Kampfhubschrauber. Diese Aufgabe \u00fcbernimmt der AH-64 Apache. Was die US-Armee bei Project Convergence Capstone 6 demonstrierte, ist etwas Ungew\u00f6hnlicheres und wom\u00f6glich N\u00fctzlicheres: ein Mehrzweckhubschrauber, der als Mutterschiff fungiert und Sensoren sowie Pr\u00e4zisionsangriffe weit \u00fcber die Reichweite der fest installierten Ausr\u00fcstung hinaus ausf\u00fchrt.<\/p>\r\n<div style=\"background:#f5f5f5;padding:20px;margin:24px 0\"><p style=\"margin:0 0 10px;font-weight:700;font-size:17px\">Kurzinfo<\/p><ul style=\"margin:0;padding-left:18px;line-height:1.8\"><li><strong>Ereignis:<\/strong> Project Convergence Capstone 6, Flug \u00fcber die Mojave-W\u00fcste<\/li><li><strong>ver\u00f6ffentlichtes Videomaterial:<\/strong> 31. August 2026, von Anduril Industries<\/li><li><strong>Startplattform:<\/strong> H-60M Black Hawk, Startvorrichtungen an externen Fl\u00fcgelpylonen angebracht<\/li><li><strong>Waffe:<\/strong> Anduril Altius-700-Familie; die bewaffnete Altius-700M tr\u00e4gt einen Sprengkopf von bis zu 15 kg (33 lb)<\/li><li><strong>Erreichen:<\/strong> Altius-700M Reichweite von ungef\u00e4hr 160 km (100 Meilen), Laufzeit etwa 75 Minuten<\/li><li><strong>Zum Vergleich:<\/strong> Die AGM-114 Hellfire erreicht eine Reichweite von etwa 11 km.<\/li><\/ul><\/div>\r\n<h2 style=\"padding-top:22px\">Was geschah tats\u00e4chlich in der Mojave-W\u00fcste?<\/h2>\r\n<p>Laut Anduril setzte eine H-60M-Besatzung ein Altius-700-\u201cJagd- und Kampfteam\u201d ein, das das Ziel autonom lokalisierte, die Daten innerhalb der Formation weiterleitete und angriff. Anders ausgedr\u00fcckt: Die Hubschrauberbesatzung steuerte die Drohne nicht selbst zum Ziel. Sie setzte sie ab, und die Drohnen erledigten den Rest selbstst\u00e4ndig.<\/p>\r\n<p>Die Mojave-W\u00fcste wurde nicht aufgrund ihrer Landschaft ausgew\u00e4hlt. Die extreme Hitze dort erm\u00f6glichte es der Armee, die Umweltbest\u00e4ndigkeit des Systems sowie seine Vernetzungsf\u00e4higkeit zu testen. Zuvor hatte es im Juni dreit\u00e4gige Flugtests in Fort AP Hill, Virginia, gegeben, bei denen die Besatzungen des H-60M mehrere Mittelstrecken-Fallschirmsysteme starteten und steuerten.<\/p>\r\n<div style=\"max-width:550px;margin:0 auto 28px\"><iframe class=\"skip-lazy\" data-no-lazy=\"1\" loading=\"eager\" src=\"https:\/\/platform.twitter.com\/embed\/Tweet.html?id=2094508311261687915&theme=light\" style=\"width:100%;height:600px;border:none;overflow:hidden\" allowfullscreen><\/iframe><\/div>\r\n<p>Anduril bezeichnete die Fahrzeuge im Video lediglich als Altius-700, doch die Aufnahmen zeigen, wie eines davon ein offenbar gepanzertes Bodenfahrzeug zerst\u00f6rt. Im Vorfeld der \u00dcbung hatte die Armee den bewaffneten Altius-700M als die Langstreckenpr\u00e4zisionsmunition identifiziert, die sie von einem Black Hawk aus abfeuern wollte. Dies deutet stark darauf hin, dass es sich bei dem kinetischen Fahrzeug im Video um einen 700M handelt.<\/p>\r\n<div style=\"background:#f8f9fa;border-left:4px solid #1565c0;padding:20px 22px;margin:18px 0 24px;font-size:16px;line-height:1.7\"><em>\u201cDer erfolgreiche Einsatz von luftgest\u00fctzten Effekten aus einem Black Hawk ist mehr als ein Meilenstein, er ist ein Quantensprung. Durch die Vergr\u00f6\u00dferung ihrer Reichweite und die Steigerung ihrer T\u00f6dlichkeit ver\u00e4ndern wir die Gefechtsfeldgeometrie und verschaffen unseren Soldaten einen entscheidenden Vorteil.\u201d<\/em><div style=\"margin-top:10px;font-size:14px;color:#555\"><strong>Brigadegeneral Kevin Chaney<\/strong> \u2014 Stellvertretender Leiter der Portfolioakquisition f\u00fcr Man\u00f6verluftfahrt, US-Armee<\/div><\/div>\r\n<h2 style=\"padding-top:22px\">Warum ausgerechnet ein Mehrzweckhubschrauber?<\/h2>\r\n<p>Unbemannte, von Flugzeugen abgefeuerte Systeme \u00fcbernehmen gef\u00e4hrliche Aufgaben wie Aufkl\u00e4rung, Zielerfassung, elektronische Kampff\u00fchrung, Kommunikationsweiterleitung, T\u00e4uschung oder den eigentlichen Angriff. Der Vorteil liegt auf der Hand: Ein nicht-kinetisches System kann weit vor der Formation aufkl\u00e4ren, w\u00e4hrend der bemannte Hubschrauber au\u00dferhalb der Gefahrenzone bleibt. Ein bewaffnetes System kann Ziele angreifen, die der Hubschrauber niemals sicher erreichen k\u00f6nnte.<\/p>\r\n<figure class=\"wp-block-image size-large\" style=\"margin:0 0 24px;width:100%\"><img data-opt-id=1950174855  fetchpriority=\"high\" decoding=\"async\" class=\"skip-lazy\" data-no-lazy=\"1\" loading=\"eager\" width=\"1024\" src=\"https:\/\/ml5psubhxdln.i.optimole.com\/cb:0e0_.b970\/w:auto\/h:auto\/q:mauto\/ig:avif\/https:\/\/migflug.com\/afterburner\/wp-content\/uploads\/sites\/4\/2026\/09\/uh-60-black-hawk-cockpit-view-dawn.jpg\" alt=\"Blick aus dem Cockpit eines UH-60 Black Hawk im Morgengrauen\" style=\"width:100%;height:auto;max-width:100%;display:block\"><figcaption style=\"font-size:13px;color:#777;text-align:center;margin-top:6px;font-style:italic\">Der Black Hawk transportiert seit vier Jahrzehnten Truppen und Fracht. Durch den Einsatz von Spezialeffekten wird er zur Kommandozentrale eines Drohnenschwarms. (Foto: US Army)<\/figcaption><\/figure>\r\n<p>Die Zahlen erkl\u00e4ren die Begeisterung. Eine Hellfire zwingt den Hubschrauber, sich dem Ziel bis auf etwa 11 Kilometer zu n\u00e4hern. Eine Altius-700M hingegen soll eine Reichweite von rund 160 Kilometern haben und dabei \u00fcber eine Stunde kreisen k\u00f6nnen. Das ist keine blo\u00dfe Reichweitenverbesserung, sondern eine v\u00f6llig neue Art der Kriegsf\u00fchrung.<\/p>\r\n<p>Sikorsky hat offen dargelegt, wohin das f\u00fchrt, und es geht nicht um eine Drohne nach der anderen.<\/p>\r\n<div style=\"background:#f8f9fa;border-left:4px solid #5C91FF;padding:20px 22px;margin:18px 0 24px;font-size:16px;line-height:1.7\"><em>\u201cWir planen nicht, nur ein System gleichzeitig einzusetzen. Wir gehen davon aus, dass mehrere Systeme gleichzeitig operieren werden, und das zuk\u00fcnftige Gefechtsfeld wird eine gro\u00dfe Anzahl von Drohnen umfassen, die mit einem Mutterschiff oder einem anderen Kontrollknotenpunkt kommunizieren m\u00fcssen. Der Black Hawk wird in der Lage sein, diese Rolle zu \u00fcbernehmen.\u201d<\/em><div style=\"margin-top:10px;font-size:14px;color:#555\"><strong>Jason Wrigley<\/strong> \u2014 Direktor f\u00fcr Gesch\u00e4ftsentwicklung f\u00fcr Heeres- und Luftwaffensysteme, Sikorsky<\/div><\/div>\r\n<h2 style=\"padding-top:22px\">Der ruhige Teil: Dies ist Inkrement 1<\/h2>\r\n<p>Die US-Armee beschreibt die erste Ausbaustufe der F\u00e4higkeit zum Einsatz von Fernkampfeffekten als ein vollst\u00e4ndig staatseigenes und -entwickeltes System, das in Zusammenarbeit mit dem Utility Helicopters Project Office und dem Aviation and Missile Center des DEVCOM entwickelt wurde. Die Altius-Familie von Anduril geh\u00f6rte zu den Systemen, die bei Capstone 6 zum Einsatz kamen, obwohl die Armee nicht alle verwendeten Effekte \u00f6ffentlich benannt hat.<\/p>\r\n<p>Der unbemannte U-Hawk wird derweil mit einem internen Startsystem ausgestattet, sodass die Effekte im Inneren des Flugzeugs und nicht an den Tragfl\u00e4chen transportiert werden. Verbindet man diese beiden Aspekte, wird das Ziel deutlich: ein unbemannter Black Hawk, vollgepackt mit kleinen autonomen Waffen, der allen anderen bemannten Flugzeugen vorausfliegt.<\/p>\r\n<div style=\"position:relative;padding-bottom:56.25%;height:0;overflow:hidden;margin:24px 0\"><iframe class=\"skip-lazy\" data-no-lazy=\"1\" loading=\"eager\" src=\"https:\/\/www.youtube.com\/embed\/4RL_sHgEYww\" style=\"position:absolute;top:0;left:0;width:100%;height:100%;border:0\" allowfullscreen><\/iframe><\/div>\r\n<p><em>Quellen: The Aviationist, Anduril Industries, TWZ, Janes und Automated Decision Research.<\/em><\/p>\r\n<div style=\"background:#f0f4ff;border-left:4px solid #5C91FF;padding:16px 20px;margin:32px 0 8px\"><p style=\"margin:0 0 8px;font-weight:600;color:#333\">\u00c4hnliche Beitr\u00e4ge<\/p><p style=\"margin:4px 0\"><a href=\"https:\/\/migflug.com\/afterburner\/de\/cca-increment-2-concept-refinement-new-engine-classes-2026\/\">CCA-Inkrement 2: Neue Motorenklassen betreten den Rahmen<\/a><\/p><p style=\"margin:4px 0\"><a href=\"https:\/\/migflug.com\/afterburner\/de\/shield-ai-x-bat-navy-diu-50-million-air-force-holds-off-2026\/\">Shield AI X-BAT sichert sich Gelder der Marine, w\u00e4hrend die Luftwaffe abwartet.<\/a><\/p><\/div>","protected":false},"excerpt":{"rendered":"<p>The U.S. Army just turned its workhorse troop taxi into a launch platform for autonomous killers. Footage released by Anduril on 31 August shows an H-60M Black Hawk rocket-launching an Altius-700 from an external pylon, the drone streaking away across the Mojave before a formation of them hunts down a target on its own. The [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":19016940,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"editor_notices":[],"footnotes":""},"categories":[664,670],"tags":[],"class_list":["post-19017348","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-military-aviation","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Altius-700: A Black Hawk Rocket-Launches Anduril&#039;s Drone | MiGFlug<\/title>\n<meta name=\"description\" content=\"The US Army rocket-launched an Altius-700 from an H-60M Black Hawk at Project Convergence. Inside the test, the drone and what it means.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/migflug.com\/afterburner\/de\/altius-700-black-hawk-raketenstart-anduril-projekt-konvergenz-2026\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Altius-700: A Black Hawk Rocket-Launches Anduril&#039;s Drone | MiGFlug\" \/>\n<meta property=\"og:description\" content=\"The US Army rocket-launched an Altius-700 from an H-60M Black Hawk at Project Convergence. Inside the test, the drone and what it means.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/migflug.com\/afterburner\/de\/altius-700-black-hawk-raketenstart-anduril-projekt-konvergenz-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Afterburner - MiGFlug&#039;s Magazine\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MiGFlug\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-01T18:49:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T06:46:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ml5psubhxdln.i.optimole.com\/cb:0e0_.b970\/w:auto\/h:auto\/q:mauto\/ig:avif\/https:\/\/migflug.com\/afterburner\/wp-content\/uploads\/sites\/4\/2026\/09\/us-army-uh-60m-black-hawk-launched-effects.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Joseph Duncan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@migflug\" \/>\n<meta name=\"twitter:site\" content=\"@migflug\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joseph Duncan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/migflug.com\\\/afterburner\\\/altius-700-black-hawk-rocket-launch-anduril-project-convergence-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/migflug.com\\\/afterburner\\\/altius-700-black-hawk-rocket-launch-anduril-project-convergence-2026\\\/\"},\"author\":{\"name\":\"Joseph Duncan\",\"@id\":\"https:\\\/\\\/migflug.com\\\/afterburner\\\/it\\\/#\\\/schema\\\/person\\\/b969321b26faa21775f0c40e141cdf85\"},\"headline\":\"Altius-700: A Black Hawk Rocket-Launches Anduril&#8217;s Drone\",\"datePublished\":\"2026-09-01T18:49:10+00:00\",\"dateModified\":\"2026-09-02T06:46:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/migflug.com\\\/afterburner\\\/altius-700-black-hawk-rocket-launch-anduril-project-convergence-2026\\\/\"},\"wordCount\":783,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/migflug.com\\\/afterburner\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/migflug.com\\\/afterburner\\\/altius-700-black-hawk-rocket-launch-anduril-project-convergence-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/migflug.com\\/afterburner\\/wp-content\\/uploads\\/sites\\/4\\/2026\\/09\\/us-army-uh-60m-black-hawk-launched-effects.jpg\",\"articleSection\":[\"Military Aviation\",\"News\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/migflug.com\\\/afterburner\\\/altius-700-black-hawk-rocket-launch-anduril-project-convergence-2026\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/migflug.com\\\/afterburner\\\/altius-700-black-hawk-rocket-launch-anduril-project-convergence-2026\\\/\",\"url\":\"https:\\\/\\\/migflug.com\\\/afterburner\\\/altius-700-black-hawk-rocket-launch-anduril-project-convergence-2026\\\/\",\"name\":\"Altius-700: A Black Hawk Rocket-Launches Anduril's Drone | MiGFlug\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/migflug.com\\\/afterburner\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/migflug.com\\\/afterburner\\\/altius-700-black-hawk-rocket-launch-anduril-project-convergence-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/migflug.com\\\/afterburner\\\/altius-700-black-hawk-rocket-launch-anduril-project-convergence-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\/\\/migflug.com\\/afterburner\\/wp-content\\/uploads\\/sites\\/4\\/2026\\/09\\/us-army-uh-60m-black-hawk-launched-effects.jpg\",\"datePublished\":\"2026-09-01T18:49:10+00:00\",\"dateModified\":\"2026-09-02T06:46:21+00:00\",\"description\":\"The US Army rocket-launched an Altius-700 from an H-60M Black Hawk at Project Convergence. Inside the test, the drone and what it means.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/migflug.com\\\/afterburner\\\/altius-700-black-hawk-rocket-launch-anduril-project-convergence-2026\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/migflug.com\\\/afterburner\\\/altius-700-black-hawk-rocket-launch-anduril-project-convergence-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/migflug.com\\\/afterburner\\\/altius-700-black-hawk-rocket-launch-anduril-project-convergence-2026\\\/#primaryimage\",\"url\":\"https:\\/\\/migflug.com\\/afterburner\\/wp-content\\/uploads\\/sites\\/4\\/2026\\/09\\/us-army-uh-60m-black-hawk-launched-effects.jpg\",\"contentUrl\":\"https:\\/\\/migflug.com\\/afterburner\\/wp-content\\/uploads\\/sites\\/4\\/2026\\/09\\/us-army-uh-60m-black-hawk-launched-effects.jpg\",\"width\":1280,\"height\":853,\"caption\":\"A US Army UH-60M Black Hawk, the type used in the Altius-700 launched-effects tests\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/migflug.com\\\/afterburner\\\/altius-700-black-hawk-rocket-launch-anduril-project-convergence-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/migflug.com\\\/afterburner\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Altius-700: A Black Hawk Rocket-Launches Anduril&#8217;s Drone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/migflug.com\\\/afterburner\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/migflug.com\\\/afterburner\\\/it\\\/\",\"name\":\"Afterburner - MiGFlug's Magazine\",\"description\":\"for those interested in flying military jets and aviation related  topics\",\"publisher\":{\"@id\":\"https:\\\/\\\/migflug.com\\\/afterburner\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/migflug.com\\\/afterburner\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/migflug.com\\\/afterburner\\\/it\\\/#organization\",\"name\":\"MiGFlug GmbH\",\"url\":\"https:\\\/\\\/migflug.com\\\/afterburner\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/migflug.com\\\/afterburner\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\/\\/ml5psubhxdln.i.optimole.com\\/cb:0e0_.b970\\/w:897\\/h:278\\/q:mauto\\/ig:avif\\/https:\\/\\/migflug.com\\/afterburner\\/wp-content\\/uploads\\/sites\\/4\\/2026\\/06\\/MIGFLUG_LOGO-no-background.png\",\"contentUrl\":\"https:\\/\\/ml5psubhxdln.i.optimole.com\\/cb:0e0_.b970\\/w:897\\/h:278\\/q:mauto\\/ig:avif\\/https:\\/\\/migflug.com\\/afterburner\\/wp-content\\/uploads\\/sites\\/4\\/2026\\/06\\/MIGFLUG_LOGO-no-background.png\",\"width\":897,\"height\":278,\"caption\":\"MiGFlug GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/migflug.com\\\/afterburner\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MiGFlug\\\/\",\"https:\\\/\\\/x.com\\\/migflug\",\"https:\\\/\\\/www.instagram.com\\\/migflug\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/MiGFlug\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/migflug.com\\\/\",\"https:\\\/\\\/www.pinterest.ch\\\/migflug\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/migflug.com\\\/afterburner\\\/it\\\/#\\\/schema\\\/person\\\/b969321b26faa21775f0c40e141cdf85\",\"name\":\"Joseph Duncan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd6d4cc4c63e8c05a1f5db9308c285d6dd9753e6d076a39f8c5ed9a7d9f7c523?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd6d4cc4c63e8c05a1f5db9308c285d6dd9753e6d076a39f8c5ed9a7d9f7c523?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cd6d4cc4c63e8c05a1f5db9308c285d6dd9753e6d076a39f8c5ed9a7d9f7c523?s=96&d=mm&r=g\",\"caption\":\"Joseph Duncan\"},\"description\":\"Joseph Duncan covers breaking defence news \u2014 fast, sharp dispatches on the Pentagon, procurement and the world\u2019s air forces.\",\"url\":\"https:\\\/\\\/migflug.com\\\/afterburner\\\/de\\\/author\\\/josephduncan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Altius-700: Eine Black-Hawk-Rakete startet Andurils Drohne | MiGFlug","description":"Die US-Armee startete im Rahmen des Projekts Convergence eine Altius-700-Drohne mit einer H-60M Black Hawk-Hubschrauberrakete. Ein Blick hinter die Kulissen des Tests, die Drohne und ihre Bedeutung.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/migflug.com\/afterburner\/de\/altius-700-black-hawk-raketenstart-anduril-projekt-konvergenz-2026\/","og_locale":"de_DE","og_type":"article","og_title":"Altius-700: A Black Hawk Rocket-Launches Anduril's Drone | MiGFlug","og_description":"The US Army rocket-launched an Altius-700 from an H-60M Black Hawk at Project Convergence. Inside the test, the drone and what it means.","og_url":"https:\/\/migflug.com\/afterburner\/de\/altius-700-black-hawk-raketenstart-anduril-projekt-konvergenz-2026\/","og_site_name":"Afterburner - MiGFlug's Magazine","article_publisher":"https:\/\/www.facebook.com\/MiGFlug\/","article_published_time":"2026-09-01T18:49:10+00:00","article_modified_time":"2026-09-02T06:46:21+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/ml5psubhxdln.i.optimole.com\/cb:0e0_.b970\/w:auto\/h:auto\/q:mauto\/ig:avif\/https:\/\/migflug.com\/afterburner\/wp-content\/uploads\/sites\/4\/2026\/09\/us-army-uh-60m-black-hawk-launched-effects.jpg","type":"image\/jpeg"}],"author":"Joseph Duncan","twitter_card":"summary_large_image","twitter_creator":"@migflug","twitter_site":"@migflug","twitter_misc":{"Written by":"Joseph Duncan","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/migflug.com\/afterburner\/altius-700-black-hawk-rocket-launch-anduril-project-convergence-2026\/#article","isPartOf":{"@id":"https:\/\/migflug.com\/afterburner\/altius-700-black-hawk-rocket-launch-anduril-project-convergence-2026\/"},"author":{"name":"Joseph Duncan","@id":"https:\/\/migflug.com\/afterburner\/it\/#\/schema\/person\/b969321b26faa21775f0c40e141cdf85"},"headline":"Altius-700: A Black Hawk Rocket-Launches Anduril&#8217;s Drone","datePublished":"2026-09-01T18:49:10+00:00","dateModified":"2026-09-02T06:46:21+00:00","mainEntityOfPage":{"@id":"https:\/\/migflug.com\/afterburner\/altius-700-black-hawk-rocket-launch-anduril-project-convergence-2026\/"},"wordCount":783,"commentCount":0,"publisher":{"@id":"https:\/\/migflug.com\/afterburner\/it\/#organization"},"image":{"@id":"https:\/\/migflug.com\/afterburner\/altius-700-black-hawk-rocket-launch-anduril-project-convergence-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/ml5psubhxdln.i.optimole.com\/cb:0e0_.b970\/w:auto\/h:auto\/q:mauto\/ig:avif\/https:\/\/migflug.com\/afterburner\/wp-content\/uploads\/sites\/4\/2026\/09\/us-army-uh-60m-black-hawk-launched-effects.jpg","articleSection":["Military Aviation","News"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/migflug.com\/afterburner\/altius-700-black-hawk-rocket-launch-anduril-project-convergence-2026\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/migflug.com\/afterburner\/altius-700-black-hawk-rocket-launch-anduril-project-convergence-2026\/","url":"https:\/\/migflug.com\/afterburner\/altius-700-black-hawk-rocket-launch-anduril-project-convergence-2026\/","name":"Altius-700: Eine Black-Hawk-Rakete startet Andurils Drohne | MiGFlug","isPartOf":{"@id":"https:\/\/migflug.com\/afterburner\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/migflug.com\/afterburner\/altius-700-black-hawk-rocket-launch-anduril-project-convergence-2026\/#primaryimage"},"image":{"@id":"https:\/\/migflug.com\/afterburner\/altius-700-black-hawk-rocket-launch-anduril-project-convergence-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/ml5psubhxdln.i.optimole.com\/cb:0e0_.b970\/w:auto\/h:auto\/q:mauto\/ig:avif\/https:\/\/migflug.com\/afterburner\/wp-content\/uploads\/sites\/4\/2026\/09\/us-army-uh-60m-black-hawk-launched-effects.jpg","datePublished":"2026-09-01T18:49:10+00:00","dateModified":"2026-09-02T06:46:21+00:00","description":"Die US-Armee startete im Rahmen des Projekts Convergence eine Altius-700-Drohne mit einer H-60M Black Hawk-Hubschrauberrakete. Ein Blick hinter die Kulissen des Tests, die Drohne und ihre Bedeutung.","breadcrumb":{"@id":"https:\/\/migflug.com\/afterburner\/altius-700-black-hawk-rocket-launch-anduril-project-convergence-2026\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/migflug.com\/afterburner\/altius-700-black-hawk-rocket-launch-anduril-project-convergence-2026\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/migflug.com\/afterburner\/altius-700-black-hawk-rocket-launch-anduril-project-convergence-2026\/#primaryimage","url":"https:\/\/ml5psubhxdln.i.optimole.com\/cb:0e0_.b970\/w:auto\/h:auto\/q:mauto\/ig:avif\/https:\/\/migflug.com\/afterburner\/wp-content\/uploads\/sites\/4\/2026\/09\/us-army-uh-60m-black-hawk-launched-effects.jpg","contentUrl":"https:\/\/ml5psubhxdln.i.optimole.com\/cb:0e0_.b970\/w:auto\/h:auto\/q:mauto\/ig:avif\/https:\/\/migflug.com\/afterburner\/wp-content\/uploads\/sites\/4\/2026\/09\/us-army-uh-60m-black-hawk-launched-effects.jpg","width":1280,"height":853,"caption":"A US Army UH-60M Black Hawk, the type used in the Altius-700 launched-effects tests"},{"@type":"BreadcrumbList","@id":"https:\/\/migflug.com\/afterburner\/altius-700-black-hawk-rocket-launch-anduril-project-convergence-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/migflug.com\/afterburner\/it\/"},{"@type":"ListItem","position":2,"name":"Altius-700: A Black Hawk Rocket-Launches Anduril&#8217;s Drone"}]},{"@type":"WebSite","@id":"https:\/\/migflug.com\/afterburner\/it\/#website","url":"https:\/\/migflug.com\/afterburner\/it\/","name":"Afterburner \u2013 MiGFlugs Magazin","description":"F\u00fcr alle, die sich f\u00fcr das Fliegen von Milit\u00e4rjets und verwandte Luftfahrtthemen interessieren.","publisher":{"@id":"https:\/\/migflug.com\/afterburner\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/migflug.com\/afterburner\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/migflug.com\/afterburner\/it\/#organization","name":"MiGFlug GmbH","url":"https:\/\/migflug.com\/afterburner\/it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/migflug.com\/afterburner\/it\/#\/schema\/logo\/image\/","url":"https:\/\/ml5psubhxdln.i.optimole.com\/cb:0e0_.b970\/w:897\/h:278\/q:mauto\/ig:avif\/https:\/\/migflug.com\/afterburner\/wp-content\/uploads\/sites\/4\/2026\/06\/MIGFLUG_LOGO-no-background.png","contentUrl":"https:\/\/ml5psubhxdln.i.optimole.com\/cb:0e0_.b970\/w:897\/h:278\/q:mauto\/ig:avif\/https:\/\/migflug.com\/afterburner\/wp-content\/uploads\/sites\/4\/2026\/06\/MIGFLUG_LOGO-no-background.png","width":897,"height":278,"caption":"MiGFlug GmbH"},"image":{"@id":"https:\/\/migflug.com\/afterburner\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MiGFlug\/","https:\/\/x.com\/migflug","https:\/\/www.instagram.com\/migflug\/","https:\/\/www.youtube.com\/user\/MiGFlug","https:\/\/www.linkedin.com\/company\/migflug.com\/","https:\/\/www.pinterest.ch\/migflug\/"]},{"@type":"Person","@id":"https:\/\/migflug.com\/afterburner\/it\/#\/schema\/person\/b969321b26faa21775f0c40e141cdf85","name":"Joseph Duncan","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/cd6d4cc4c63e8c05a1f5db9308c285d6dd9753e6d076a39f8c5ed9a7d9f7c523?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cd6d4cc4c63e8c05a1f5db9308c285d6dd9753e6d076a39f8c5ed9a7d9f7c523?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cd6d4cc4c63e8c05a1f5db9308c285d6dd9753e6d076a39f8c5ed9a7d9f7c523?s=96&d=mm&r=g","caption":"Joseph Duncan"},"description":"Joseph Duncan berichtet \u00fcber aktuelle Verteidigungsnachrichten \u2013 schnelle, pr\u00e4gnante Meldungen \u00fcber das Pentagon, Beschaffungswesen und die Luftstreitkr\u00e4fte der Welt.","url":"https:\/\/migflug.com\/afterburner\/de\/author\/josephduncan\/"}]}},"_links":{"self":[{"href":"https:\/\/migflug.com\/afterburner\/de\/wp-json\/wp\/v2\/posts\/19017348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/migflug.com\/afterburner\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/migflug.com\/afterburner\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/migflug.com\/afterburner\/de\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/migflug.com\/afterburner\/de\/wp-json\/wp\/v2\/comments?post=19017348"}],"version-history":[{"count":2,"href":"https:\/\/migflug.com\/afterburner\/de\/wp-json\/wp\/v2\/posts\/19017348\/revisions"}],"predecessor-version":[{"id":19187551,"href":"https:\/\/migflug.com\/afterburner\/de\/wp-json\/wp\/v2\/posts\/19017348\/revisions\/19187551"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/migflug.com\/afterburner\/de\/wp-json\/wp\/v2\/media\/19016940"}],"wp:attachment":[{"href":"https:\/\/migflug.com\/afterburner\/de\/wp-json\/wp\/v2\/media?parent=19017348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/migflug.com\/afterburner\/de\/wp-json\/wp\/v2\/categories?post=19017348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/migflug.com\/afterburner\/de\/wp-json\/wp\/v2\/tags?post=19017348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}