{"id":257,"date":"2017-06-08T19:10:33","date_gmt":"2017-06-08T17:10:33","guid":{"rendered":"http:\/\/migflug.com\/?page_id=257"},"modified":"2026-06-22T23:16:08","modified_gmt":"2026-06-22T21:16:08","slug":"l-29-%d8%af%d9%84%d9%81%d9%8a%d9%86-%d8%b3%d9%84%d9%88%d9%81%d8%a7%d9%83%d9%8a%d8%a7","status":"publish","type":"page","link":"https:\/\/migflug.com\/ar\/flights-prices\/l-29-delfin-slovakia\/","title":{"rendered":"L-29 \u062f\u0644\u0641\u064a\u0646 \u0641\u064a \u0633\u0644\u0648\u0641\u0627\u0643\u064a\u0627"},"content":{"rendered":"<div class=\"et_pb_section_0 et_pb_section et_pb_fullwidth_section et_section_regular et_block_section\"><div class=\"et_pb_fullwidth_image_0 et_pb_fullwidth_image et_pb_module\"><img data-opt-id=1990425093  data-opt-src=\"https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:auto\/h:auto\/q:96\/f:best\/https:\/\/migflug.com\/wp-content\/uploads\/2021\/12\/L-29-delfin-jetflug-slowakei-21.jpg\"  decoding=\"async\" src=\"data:image/svg+xml,%3Csvg%20viewBox%3D%220%200%20100%%20100%%22%20width%3D%22100%%22%20height%3D%22100%%22%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%3E%3Crect%20width%3D%22100%%22%20height%3D%22100%%22%20fill%3D%22transparent%22%2F%3E%3C%2Fsvg%3E\" width=\"2000\" height=\"600\" old-srcset=\"https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:1920\/h:576\/q:96\/f:best\/https:\/\/migflug.com\/wp-content\/uploads\/2021\/12\/L-29-delfin-jetflug-slowakei-21.jpg 2000w, https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:1280\/h:384\/q:96\/f:best\/https:\/\/migflug.com\/wp-content\/uploads\/2021\/12\/L-29-delfin-jetflug-slowakei-21.jpg 1280w, https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:980\/h:294\/q:96\/f:best\/https:\/\/migflug.com\/wp-content\/uploads\/2021\/12\/L-29-delfin-jetflug-slowakei-21.jpg 980w, https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:480\/h:144\/q:96\/f:best\/https:\/\/migflug.com\/wp-content\/uploads\/2021\/12\/L-29-delfin-jetflug-slowakei-21.jpg 480w, https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:1920\/h:576\/q:96\/f:best\/dpr:2\/https:\/\/migflug.com\/wp-content\/uploads\/2021\/12\/L-29-delfin-jetflug-slowakei-21.jpg 2x\" class=\"wp-image-3415\" title=\"L-29-\u062f\u0644\u0641\u064a\u0646-\u062c\u064a\u062a\u0641\u0644\u0648\u063a-\u0633\u0644\u0648\u0627\u0643\u064a-21\" alt=\"L-29 Delfin Jetflug \u0641\u064a \u062f\u064a\u0631 \u0633\u0644\u0648\u0627\u0643\u064a\" \/><\/div><div class=\"et_pb_fullwidth_image_1 et_pb_fullwidth_image et_pb_module\"><img data-opt-id=55909852  data-opt-src=\"https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:auto\/h:auto\/q:96\/f:best\/https:\/\/migflug.com\/wp-content\/uploads\/2021\/12\/L-29-delfin-jetflug-slowakei-mo-21.jpg\"  decoding=\"async\" src=\"data:image/svg+xml,%3Csvg%20viewBox%3D%220%200%20100%%20100%%22%20width%3D%22100%%22%20height%3D%22100%%22%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%3E%3Crect%20width%3D%22100%%22%20height%3D%22100%%22%20fill%3D%22transparent%22%2F%3E%3C%2Fsvg%3E\" width=\"900\" height=\"700\" old-srcset=\"https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:900\/h:700\/q:96\/f:best\/https:\/\/migflug.com\/wp-content\/uploads\/2021\/12\/L-29-delfin-jetflug-slowakei-mo-21.jpg 900w, https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:480\/h:373\/q:96\/f:best\/https:\/\/migflug.com\/wp-content\/uploads\/2021\/12\/L-29-delfin-jetflug-slowakei-mo-21.jpg 480w, https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:900\/h:700\/q:96\/f:best\/dpr:2\/https:\/\/migflug.com\/wp-content\/uploads\/2021\/12\/L-29-delfin-jetflug-slowakei-mo-21.jpg 2x\" class=\"wp-image-3416\" title=\"L-29-\u062f\u0644\u0641\u064a\u0646-\u062c\u064a\u062a\u0641\u0644\u0648\u063a-\u0633\u0644\u0648\u0627\u0643\u064a-\u0645\u0648-21\" alt=\"L-29 Delfin Jetflug \u0641\u064a \u062f\u064a\u0631 \u0633\u0644\u0648\u0627\u0643\u064a\" \/><\/div><\/div><div class=\"et_pb_section_1 et_pb_section et_section_regular et_block_section\"><div class=\"et_pb_row_0 et_pb_row et_block_row\"><div class=\"et_pb_column_0 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_0 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h2>\u0631\u062d\u0644\u0629 \u0637\u0627\u0626\u0631\u0629 \u0625\u0644-29 \u062f\u0644\u0641\u064a\u0646 \u0627\u0644\u0646\u0641\u0627\u062b\u0629 \u0641\u064a \u0633\u0644\u0648\u0641\u0627\u0643\u064a\u0627<\/h2>\n<p class=\"main-text\">1950 \u064a\u0648\u0631\u0648 \u0644\u0631\u062d\u0644\u0629 \u0645\u062f\u062a\u0647\u0627 20 \u062f\u0642\u064a\u0642\u0629<br \/>2450 \u064a\u0648\u0631\u0648 \u0644\u0631\u062d\u0644\u0629 \u0645\u062f\u062a\u0647\u0627 30 \u062f\u0642\u064a\u0642\u0629<\/p>\n<\/div><\/div><div class=\"et_pb_text_1 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p>\u0627\u0644\u0644\u063a\u0627\u062a \u0627\u0644\u0645\u0633\u062a\u062e\u062f\u0645\u0629:\u00a0 <img data-opt-id=2087983896  data-opt-src=\"https:\/\/migflug.com\/wp-content\/uploads\/2023\/12\/flagge-usa-23.png\"  decoding=\"async\" class=\"alignnone wp-image-6690\" src=\"data:image/svg+xml,%3Csvg%20viewBox%3D%220%200%20100%%20100%%22%20width%3D%22100%%22%20height%3D%22100%%22%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%3E%3Crect%20width%3D%22100%%22%20height%3D%22100%%22%20fill%3D%22transparent%22%2F%3E%3C%2Fsvg%3E\" alt=\"\" width=\"20\" height=\"13\" \/>\u00a0 \u00a0<img data-opt-id=250956237  data-opt-src=\"https:\/\/migflug.com\/wp-content\/uploads\/2024\/06\/sprache-slowakisch.png\"  decoding=\"async\" class=\"alignnone wp-image-7505\" src=\"data:image/svg+xml,%3Csvg%20viewBox%3D%220%200%20100%%20100%%22%20width%3D%22100%%22%20height%3D%22100%%22%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%3E%3Crect%20width%3D%22100%%22%20height%3D%22100%%22%20fill%3D%22transparent%22%2F%3E%3C%2Fsvg%3E\" alt=\"\" width=\"20\" height=\"13\" \/><\/p>\n<\/div><\/div><\/div><\/div><div class=\"et_pb_row_1 et_pb_row et_pb_row_4col et_block_row et_block_row_4col\"><div class=\"et_pb_column_1 et_pb_column et_pb_column_1_4 et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_0_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_0 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/book.migflug.com\/?location=SK-SLIAC-L29\" id=\"btn-top-book\">\u0627\u062d\u062c\u0632 \u0631\u062d\u0644\u062a\u0643<\/a><\/div><\/div><div class=\"et_pb_column_2 et_pb_column et_pb_column_1_4 et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_1_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_1 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/book.migflug.com\/?location=SK-SLIAC-L29&#038;isgift=ADDON-GIFT\" id=\"btn-top-gift\">\u0627\u0634\u062a\u0631\u0650 \u0642\u0633\u064a\u0645\u0629 \u0647\u062f\u064a\u0629<\/a><\/div><\/div><div class=\"et_pb_column_3 et_pb_column et_pb_column_1_4 et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_2_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_2 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/migflug.com\/ar\/%d9%84%d9%84%d9%85%d8%b2%d9%8a%d8%af-%d9%85%d9%86-%d8%a7%d9%84%d9%85%d8%b9%d9%84%d9%88%d9%85%d8%a7%d8%aa\/?params=displaylocation&#038;location=SK-SLIAC\" id=\"btn-top-info\">\u0637\u0644\u0628 \u0645\u0639\u0644\u0648\u0645\u0627\u062a<\/a><\/div><\/div><div class=\"et_pb_column_4 et_pb_column et_pb_column_1_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_3_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_3 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/migflug.as.me\/schedule.php?appointmentType=11656085\" target=\"_blank\">\u062a\u062d\u0642\u0642 \u0645\u0646 \u0627\u0644\u062a\u0648\u0641\u0631<\/a><\/div><\/div><\/div><\/div><div class=\"et_pb_section_2 et_pb_section et_section_regular et_block_section\"><div class=\"et_pb_row_2 et_pb_row et_block_row\"><div class=\"et_pb_column_5 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_2 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h1>\u0631\u062d\u0644\u0629 \u0637\u0627\u0626\u0631\u0629 \u0625\u0644-29 \u062f\u0644\u0641\u064a\u0646 \u0627\u0644\u0646\u0641\u0627\u062b\u0629 \u0641\u064a \u0633\u0644\u0648\u0641\u0627\u0643\u064a\u0627<\/h1>\n<\/div><\/div><div class=\"et_pb_text_3 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p class=\"bodytext\">\u0627\u0644 <a href=\"https:\/\/migflug.com\/ar\/%d8%a7%d9%84%d8%b7%d8%a7%d8%a6%d8%b1%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%a7%d8%ab%d8%a9\/l-29-delfin\/\">\u0625\u0644-29 \u062f\u0644\u0641\u064a\u0646<\/a> \u0647\u064a \u0637\u0627\u0626\u0631\u0629 \u062a\u062f\u0631\u064a\u0628 \u0646\u0641\u0627\u062b\u0629 \u0628\u0633\u064a\u0637\u0629 \u0648\u0645\u062a\u064a\u0646\u0629 \u0630\u0627\u062a \u0633\u062c\u0644 \u0623\u0645\u0627\u0646 \u0645\u062a\u0645\u064a\u0632. \u0643\u0627\u0646\u062a \u0637\u0627\u0626\u0631\u0629 \u0627\u0644\u062a\u062f\u0631\u064a\u0628 \u0627\u0644\u0646\u0641\u0627\u062b\u0629 \u0641\u064a \u0627\u0644\u0634\u0631\u0642\u060c \u0648\u0634\u063a\u0651\u0644\u062a\u0647\u0627 15 \u062f\u0648\u0644\u0629 \u0645\u0646 \u062f\u0648\u0644 \u062d\u0644\u0641 \u0648\u0627\u0631\u0633\u0648. \u0643\u0645\u0627 \u0623\u0646\u0647\u0627 \u062a\u064f\u0639\u062a\u0628\u0631 &quot;\u0623\u0635\u0644&quot; \u0627\u0644\u0637\u0627\u0626\u0631\u0627\u062a \u0627\u0644\u0646\u0641\u0627\u062b\u0629. <a href=\"https:\/\/migflug.com\/ar\/%d9%85%d8%b9%d9%84%d9%88%d9%85%d8%a7%d8%aa-%d8%b9%d9%86%d8%a7\/\">\u0645\u064a\u063a\u0641\u0644\u0648\u063a<\/a> \u0627\u0644\u0637\u0627\u0626\u0631\u0629 \u0627\u0644\u0646\u0641\u0627\u062b\u0629 \u0627\u0644\u0642\u064a\u0627\u0633\u064a\u0629\u060c <a href=\"https:\/\/migflug.com\/ar\/%d8%a7%d9%84%d8%b7%d8%a7%d8%a6%d8%b1%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%a7%d8%ab%d8%a9\/39-%d9%82%d8%b7%d8%b1%d8%b3\/\">\u0625\u0644-39 \u0623\u0644\u0628\u0627\u062a\u0631\u0648\u0633<\/a>.<\/p>\n<\/div><\/div><div class=\"et_pb_text_4 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h2>\u0637\u0627\u0626\u0631\u0629 Aero L-29 Delfin \u0631\u0642\u0645 \u0627\u0644\u062a\u0633\u0644\u0633\u0644 39 4645<\/h2>\n<p class=\"bodytext\">\u0627\u0644\u0623\u064a\u0631\u0648 <a href=\"https:\/\/migflug.com\/ar\/%d8%a7%d9%84%d8%b7%d8%a7%d8%a6%d8%b1%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%a7%d8%ab%d8%a9\/l-29-delfin\/\">\u0625\u0644-29 \u062f\u0644\u0641\u064a\u0646<\/a> \u0642\u0627\u0645\u062a \u0627\u0644\u0637\u0627\u0626\u0631\u0629 \u0630\u0627\u062a \u0627\u0644\u0631\u0642\u0645 \u0627\u0644\u062a\u0633\u0644\u0633\u0644\u064a 39 4645 \u0628\u0623\u0648\u0644 \u0631\u062d\u0644\u0629 \u0644\u0647\u0627 \u0641\u064a 16 \u0645\u0627\u0631\u0633 1972\u060c \u0648\u0633\u064f\u0644\u0645\u062a \u0625\u0644\u0649 \u0627\u0644\u0627\u062a\u062d\u0627\u062f \u0627\u0644\u0633\u0648\u0641\u064a\u062a\u064a \u0628\u0639\u062f \u0623\u0633\u0628\u0648\u0639. \u0648\u0642\u062f \u0634\u063a\u0651\u0644\u0647\u0627 \u0645\u0631\u0643\u0632 \u0644\u064a\u0628\u0643 \u0644\u0644\u062a\u062f\u0631\u064a\u0628 \u0639\u0644\u0649 \u0627\u0644\u0637\u064a\u0631\u0627\u0646 (DOSAAF SSSR) \u062d\u062a\u0649 \u0631\u062d\u0644\u062a\u0647\u0627 \u0627\u0644\u0623\u062e\u064a\u0631\u0629 \u0641\u064a 9 \u0623\u0643\u062a\u0648\u0628\u0631 1991\u060c \u0628\u0625\u062c\u0645\u0627\u0644\u064a 7111 \u0631\u062d\u0644\u0629 \u0641\u064a 2821.06 \u0633\u0627\u0639\u0629 \u0637\u064a\u0631\u0627\u0646.<\/p>\n<p class=\"bodytext\">\u0641\u064a \u0645\u0627\u064a\u0648 2011\u060c \u062e\u0636\u0639\u062a \u0627\u0644\u0637\u0627\u0626\u0631\u0629 \u0644\u0644\u0641\u062d\u0635 \u0648\u0646\u064f\u0642\u0644\u062a \u0625\u0644\u0649 \u0645\u0631\u0643\u0632 \u0635\u064a\u0627\u0646\u0629 \u0641\u064a \u0625\u0633\u062a\u0648\u0646\u064a\u0627. \u0623\u064f\u062c\u0631\u064a\u062a \u0623\u0648\u0644 \u0631\u062d\u0644\u0629 \u062a\u062c\u0631\u064a\u0628\u064a\u0629 \u0644\u0647\u0627 \u0641\u064a 11 \u0623\u0643\u062a\u0648\u0628\u0631 2013\u060c \u0648\u0628\u0639\u062f \u0625\u062a\u0645\u0627\u0645 \u0627\u0644\u0635\u064a\u0627\u0646\u0629\u060c \u0646\u064f\u0642\u0644\u062a \u0627\u0644\u0637\u0627\u0626\u0631\u0629 \u062c\u0648\u0627\u064b \u0625\u0644\u0649 \u0633\u0644\u0648\u0641\u0627\u0643\u064a\u0627 \u0641\u064a 18 \u0641\u0628\u0631\u0627\u064a\u0631 2014\u060c \u062d\u064a\u062b \u064a\u064f\u0634\u063a\u0644\u0647\u0627 \u0627\u0644\u0622\u0646 \u0637\u064a\u0627\u0631\u0648\u0646 \u0639\u0633\u0643\u0631\u064a\u0648\u0646 \u0633\u0627\u0628\u0642\u0648\u0646.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"et_pb_section_3 et_pb_section et_section_regular et_block_section\"><div class=\"et_pb_row_3 et_pb_row et_pb_gutters1 et_block_row et_pb_row_fullwidth\"><div class=\"et_pb_column_6 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_image_0 et_pb_image et_pb_image_sticky et_pb_module et_block_module\"><span class=\"et_pb_image_wrap\"><img data-opt-id=1257989088  data-opt-src=\"https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:auto\/h:auto\/q:96\/f:best\/https:\/\/migflug.com\/wp-content\/uploads\/2021\/12\/L-29-delfin-jetflug-slowakei-mo-1-1-21.jpg\"  decoding=\"async\" src=\"data:image/svg+xml,%3Csvg%20viewBox%3D%220%200%20100%%20100%%22%20width%3D%22100%%22%20height%3D%22100%%22%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%3E%3Crect%20width%3D%22100%%22%20height%3D%22100%%22%20fill%3D%22transparent%22%2F%3E%3C%2Fsvg%3E\" width=\"900\" height=\"700\" old-srcset=\"https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:900\/h:700\/q:96\/f:best\/https:\/\/migflug.com\/wp-content\/uploads\/2021\/12\/L-29-delfin-jetflug-slowakei-mo-1-1-21.jpg 900w, https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:480\/h:373\/q:96\/f:best\/https:\/\/migflug.com\/wp-content\/uploads\/2021\/12\/L-29-delfin-jetflug-slowakei-mo-1-1-21.jpg 480w, https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:900\/h:700\/q:96\/f:best\/dpr:2\/https:\/\/migflug.com\/wp-content\/uploads\/2021\/12\/L-29-delfin-jetflug-slowakei-mo-1-1-21.jpg 2x\" class=\"wp-image-3454\" title=\"L-29-\u062f\u0644\u0641\u064a\u0646-\u062c\u064a\u062a\u0641\u0644\u0648\u063a-\u0633\u0644\u0648\u0627\u0643\u064a-\u0645\u0648-1-1-21\" alt=\"\u0647\u0648\u0643\u0631 \u0647\u0646\u062a\u0631 \u064a\u0637\u064a\u0631 \u0641\u064a \u062f\u064a\u0631 \u0634\u0648\u064a\u0632\" \/><\/span><\/div><\/div><div class=\"et_pb_column_7 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_image_1 et_pb_image et_pb_image_sticky et_pb_module et_block_module\"><span class=\"et_pb_image_wrap\"><img data-opt-id=34928794  data-opt-src=\"https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:auto\/h:auto\/q:96\/f:best\/https:\/\/migflug.com\/wp-content\/uploads\/2021\/12\/l-29-jet-flight-in-slovakia-21.jpg\"  decoding=\"async\" src=\"data:image/svg+xml,%3Csvg%20viewBox%3D%220%200%20100%%20100%%22%20width%3D%22100%%22%20height%3D%22100%%22%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%3E%3Crect%20width%3D%22100%%22%20height%3D%22100%%22%20fill%3D%22transparent%22%2F%3E%3C%2Fsvg%3E\" width=\"900\" height=\"700\" old-srcset=\"https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:900\/h:700\/q:96\/f:best\/https:\/\/migflug.com\/wp-content\/uploads\/2021\/12\/l-29-jet-flight-in-slovakia-21.jpg 900w, https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:480\/h:373\/q:96\/f:best\/https:\/\/migflug.com\/wp-content\/uploads\/2021\/12\/l-29-jet-flight-in-slovakia-21.jpg 480w, https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:900\/h:700\/q:96\/f:best\/dpr:2\/https:\/\/migflug.com\/wp-content\/uploads\/2021\/12\/l-29-jet-flight-in-slovakia-21.jpg 2x\" class=\"wp-image-3604\" title=\"\u0631\u062d\u0644\u0629 \u0637\u0627\u0626\u0631\u0629 \u0625\u0644-29 \u0641\u064a \u0633\u0644\u0648\u0641\u0627\u0643\u064a\u0627 21\" alt=\"\u0647\u0648\u0643\u0631 \u0647\u0646\u062a\u0631 \u064a\u0637\u064a\u0631 \u0641\u064a \u062f\u064a\u0631 \u0634\u0648\u064a\u0632\" \/><\/span><\/div><\/div><div class=\"et_pb_column_8 et_pb_column et_pb_column_1_3 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_image_2 et_pb_image et_pb_image_sticky et_pb_module et_block_module\"><span class=\"et_pb_image_wrap\"><img data-opt-id=1245190506  data-opt-src=\"https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:auto\/h:auto\/q:96\/f:best\/https:\/\/migflug.com\/wp-content\/uploads\/2021\/12\/L-29-delfin-jetflug-slowakei-mo-2-21.jpg\"  decoding=\"async\" src=\"data:image/svg+xml,%3Csvg%20viewBox%3D%220%200%20100%%20100%%22%20width%3D%22100%%22%20height%3D%22100%%22%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%3E%3Crect%20width%3D%22100%%22%20height%3D%22100%%22%20fill%3D%22transparent%22%2F%3E%3C%2Fsvg%3E\" width=\"900\" height=\"700\" old-srcset=\"https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:900\/h:700\/q:96\/f:best\/https:\/\/migflug.com\/wp-content\/uploads\/2021\/12\/L-29-delfin-jetflug-slowakei-mo-2-21.jpg 900w, https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:480\/h:373\/q:96\/f:best\/https:\/\/migflug.com\/wp-content\/uploads\/2021\/12\/L-29-delfin-jetflug-slowakei-mo-2-21.jpg 480w, https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:900\/h:700\/q:96\/f:best\/dpr:2\/https:\/\/migflug.com\/wp-content\/uploads\/2021\/12\/L-29-delfin-jetflug-slowakei-mo-2-21.jpg 2x\" class=\"wp-image-3455\" title=\"L-29-\u062f\u0644\u0641\u064a\u0646-\u062c\u064a\u062a\u0641\u0644\u0648\u063a-\u0633\u0644\u0648\u0627\u0643\u064a-\u0645\u0648-2-21\" alt=\"\u0647\u0648\u0643\u0631 \u0647\u0646\u062a\u0631 \u064a\u0637\u064a\u0631 \u0641\u064a \u062f\u064a\u0631 \u0634\u0648\u064a\u0632\" \/><\/span><\/div><\/div><\/div><\/div><div class=\"et_pb_section_4 et_pb_section et_section_regular et_block_section\"><div class=\"et_pb_row_4 et_pb_row et_block_row\"><div class=\"et_pb_column_9 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_5 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h2>\u062f\u0644\u0641\u064a\u0646 L-29 \u0628\u0633\u064a\u0637 \u0648\u0645\u062a\u064a\u0646<\/h2>\n<p class=\"bodytext\">\u064a\u064f\u0634\u062a\u0642 \u0627\u0633\u0645 \u0637\u0631\u0627\u0632 L-29 Delfin \u0645\u0646 \u062a\u0627\u0631\u064a\u062e \u0645\u0646\u0627\u0642\u0634\u0629 \u0627\u0644\u0645\u0639\u0627\u064a\u064a\u0631 \u0627\u0644\u0641\u0646\u064a\u0629\u060c \u0648\u0647\u0648 29 \u0633\u0628\u062a\u0645\u0628\u0631 1954. \u0648\u062a\u062a\u0645\u064a\u0632 \u062c\u0645\u064a\u0639 \u0645\u0639\u0627\u064a\u064a\u0631 \u062a\u0635\u0645\u064a\u0645\u0647 \u062a\u0642\u0631\u064a\u0628\u064b\u0627 \u0628\u0627\u0644\u0648\u0636\u0648\u062d \u0648\u0627\u0644\u0628\u0633\u0627\u0637\u0629. \u062a\u0648\u0641\u0631 \u0623\u062f\u0648\u0627\u062a \u0627\u0644\u062a\u062d\u0643\u0645 \u0627\u0644\u064a\u062f\u0648\u064a\u0629 \u0641\u064a \u0627\u0644\u0637\u064a\u0631\u0627\u0646\u060c \u0648\u0627\u0644\u0631\u0641\u0627\u0631\u0641 \u0627\u0644\u0643\u0628\u064a\u0631\u0629\u060c \u0648\u063a\u064a\u0631\u0647\u0627 \u0645\u0646 \u0627\u0644\u0645\u064a\u0632\u0627\u062a \u0627\u0644\u062f\u064a\u0646\u0627\u0645\u064a\u0643\u064a\u0629 \u0627\u0644\u0647\u0648\u0627\u0626\u064a\u0629\u060c \u0637\u064a\u0631\u0627\u0646\u064b\u0627 \u0645\u0633\u062a\u0642\u0631\u064b\u0627 \u0648\u0633\u0644\u0633\u064b\u0627. \u0648\u0642\u062f \u0627\u0633\u062a\u064f\u0628\u062f\u0644\u062a \u0627\u0644\u062a\u0635\u0627\u0645\u064a\u0645 \u0627\u0644\u0623\u0635\u0644\u064a\u0629 \u0644\u0645\u062d\u0631\u0643 M-701 \u0627\u0644\u0645\u062d\u0648\u0631\u064a \u0628\u062a\u0635\u0645\u064a\u0645 \u0637\u0631\u062f \u0645\u0631\u0643\u0632\u064a \u0623\u0628\u0633\u0637 \u0644\u062a\u0644\u0628\u064a\u0629 \u0645\u062a\u0637\u0644\u0628\u0627\u062a \u0627\u0644\u062a\u0634\u063a\u064a\u0644 \u0645\u0646 \u0627\u0644\u0645\u0631\u0648\u062c \u0648\u0627\u0644\u0631\u0645\u0627\u0644 \u0648\u063a\u064a\u0631\u0647\u0627 \u0645\u0646 \u0627\u0644\u0623\u0631\u0627\u0636\u064a \u063a\u064a\u0631 \u0627\u0644\u0645\u0639\u0628\u062f\u0629.<\/p>\n<p class=\"bodytext\">\u0633\u0627\u0647\u0645\u062a \u0643\u0644 \u0647\u0630\u0647 \u0627\u0644\u0639\u0648\u0627\u0645\u0644 \u0641\u064a \u062a\u062d\u0642\u064a\u0642 \u0633\u062c\u0644 \u0623\u0645\u0627\u0646 \u0645\u062a\u0645\u064a\u0632. \u0648\u0631\u063a\u0645 \u062a\u0648\u0642\u0641 \u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0637\u0627\u0626\u0631\u0629 L-29 Delfin \u0641\u064a \u0627\u0644\u062a\u062f\u0631\u064a\u0628 \u0627\u0644\u0639\u0633\u0643\u0631\u064a\u060c \u0625\u0644\u0627 \u0623\u0646\u0647\u0627 \u0644\u0627 \u062a\u0632\u0627\u0644 \u062a\u062d\u0638\u0649 \u0628\u0634\u0639\u0628\u064a\u0629 \u0648\u0627\u0633\u0639\u0629 \u0628\u064a\u0646 \u0645\u0634\u063a\u0644\u064a \u0627\u0644\u0637\u0627\u0626\u0631\u0627\u062a \u0627\u0644\u0645\u062f\u0646\u064a\u0629 \u062d\u0648\u0644 \u0627\u0644\u0639\u0627\u0644\u0645\u060c \u0628\u062f\u0621\u064b\u0627 \u0645\u0646 \u0627\u0644\u0631\u062d\u0644\u0627\u062a \u0627\u0644\u0634\u062e\u0635\u064a\u0629 \u0648\u0635\u0648\u0644\u064b\u0627 \u0625\u0644\u0649 \u0639\u0631\u0648\u0636 \u0627\u0644\u0637\u064a\u0631\u0627\u0646 \u0648\u0627\u0644\u0645\u0633\u0627\u0628\u0642\u0627\u062a \u0645\u062b\u0644 \u0633\u0628\u0627\u0642 \u0631\u064a\u0646\u0648 \u0627\u0644\u062c\u0648\u064a.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"et_pb_row_5 et_pb_row et_block_row\"><div class=\"et_pb_column_10 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_video_0 et_pb_video et_pb_module et_block_module\"><div class=\"et_pb_video_box\"><iframe hcb-fetch-image-from=\"https:\/\/www.youtube.com\/watch?v=GdiK4oPK55Q\" title=\"\u0639\u0645\u064a\u0644 MiGFlug \u064a\u0648\u0627\u062c\u0647 \u0642\u0648\u0629 \u062a\u0633\u0627\u0631\u0639 \u0647\u0627\u0626\u0644\u0629 - \u0631\u062d\u0644\u0629 \u0637\u0627\u0626\u0631\u0629 L-29 \u0627\u0644\u0646\u0641\u0627\u062b\u0629 \u0641\u064a \u0633\u0644\u0648\u0641\u0627\u0643\u064a\u0627\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/GdiK4oPK55Q?feature=oembed&amp;controls=1\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><\/div><\/div><\/div><div class=\"et_pb_row_6 et_pb_row et_block_row\"><div class=\"et_pb_column_11 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_divider_0 et_pb_divider_hidden et_pb_space et_pb_divider_position_top et_pb_module\"><div class=\"et_pb_divider_internal\"><\/div><\/div><div class=\"et_pb_text_6 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h2>\u064a\u0645\u0643\u0646\u0643 \u0627\u0644\u0637\u064a\u0631\u0627\u0646 \u0639\u0644\u0649 \u0645\u062a\u0646 \u0637\u0627\u0626\u0631\u0629 L-29 \u062f\u0644\u0641\u064a\u0646<\/h2>\n<p class=\"bodytext\">\u0645\u0642\u0627\u0631\u0646\u0629 \u0628\u0640 <a href=\"https:\/\/migflug.com\/ar\/%d8%a7%d9%84%d8%b7%d8%a7%d8%a6%d8%b1%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%a7%d8%ab%d8%a9\/39-%d9%82%d8%b7%d8%b1%d8%b3\/\">\u0625\u0644-39 \u0623\u0644\u0628\u0627\u062a\u0631\u0648\u0633<\/a>, \u060c \u0627\u0644 <a href=\"https:\/\/migflug.com\/ar\/%d8%a7%d9%84%d8%b7%d8%a7%d8%a6%d8%b1%d8%a7%d8%aa-%d8%a7%d9%84%d9%86%d9%81%d8%a7%d8%ab%d8%a9\/l-29-delfin\/\">\u0625\u0644-29 \u062f\u0644\u0641\u064a\u0646<\/a> \u064a\u064f\u0639\u062a\u0628\u0631 \u0637\u0631\u0627\u0632 L-29 Delfin \u0623\u0642\u0644 \u0643\u0641\u0627\u0621\u0629\u064b \u0645\u0646 \u062d\u064a\u062b \u0642\u0648\u0629 \u0627\u0644\u0645\u062d\u0631\u0643 \u0648\u0627\u0644\u0631\u0624\u064a\u0629 \u0645\u0646 \u0627\u0644\u0645\u0642\u0639\u062f \u0627\u0644\u062e\u0644\u0641\u064a. \u0643\u0645\u0627 \u064a\u0631\u0649 \u0645\u0639\u0638\u0645 \u0627\u0644\u0639\u0645\u0644\u0627\u0621 \u0623\u0646 \u0637\u0631\u0627\u0632 L-39 Albatros \u0623\u0643\u062b\u0631 \u062c\u0627\u0630\u0628\u064a\u0629\u064b \u0628\u0641\u0636\u0644 \u062a\u0635\u0645\u064a\u0645\u0647 \u0627\u0644\u0639\u0635\u0631\u064a. \u0645\u0639 \u0630\u0644\u0643\u060c \u0646\u0642\u062f\u0645 \u0645\u0639 \u0637\u0631\u0627\u0632 L-29 Delfin \u062a\u062c\u0631\u0628\u0629 \u0637\u064a\u0631\u0627\u0646 \u0646\u0641\u0627\u062b\u0629 \u0628\u0633\u0639\u0631\u064d \u0645\u063a\u0631\u064d \u0644\u0644\u063a\u0627\u064a\u0629. \u064a\u064f\u0639\u062f\u0651 \u0637\u0631\u0627\u0632 L-29 Delfin \u062e\u064a\u0627\u0631\u064b\u0627 \u0645\u0645\u062a\u0627\u0632\u064b\u0627 \u0644\u0644\u0639\u0645\u0644\u0627\u0621 \u0627\u0644\u0630\u064a\u0646 \u064a\u0628\u062d\u062b\u0648\u0646 \u0639\u0646 \u062a\u062c\u0631\u0628\u0629 \u0637\u064a\u0631\u0627\u0646 \u0646\u0641\u0627\u062b\u0629 \u0628\u0633\u0639\u0631\u064d \u0645\u0646\u0627\u0633\u0628. \u0628\u0631\u0646\u0627\u0645\u062c \u0627\u0644\u0637\u064a\u0631\u0627\u0646 \u0641\u064a\u0647 \u064a\u064f\u0636\u0627\u0647\u064a \u0628\u0631\u0646\u0627\u0645\u062c \u0637\u0631\u0627\u0632 L-39 Albatros.<\/p>\n<ul>\n<li>\u0644\u0641\u0627\u0626\u0641<\/li>\n<li>\u0625\u064a\u0645\u0644\u0645\u0627\u0646 \u064a\u0642\u0644\u0628<\/li>\n<li>\u0627\u0644\u062a\u0643\u0631\u0627\u0631<\/li>\n<li>\u0633\u0628\u0644\u062a-\u0625\u0633<\/li>\n<li>\u0627\u0644\u062a\u0633\u0644\u0642 \u0627\u0644\u0631\u064a\u0627\u0636\u064a \u0648\u0627\u0644\u063a\u0648\u0635 \u0627\u0644\u0639\u0645\u0648\u062f\u064a<\/li>\n<li>\u0645\u0637\u0627\u0631\u062f\u0629 \u0627\u0644\u0630\u064a\u0644<\/li>\n<li>\u0625\u0646 \u0623\u0645\u0643\u0646: \u0627\u0644\u062a\u062d\u0644\u064a\u0642 \u0628\u0633\u0631\u0639\u0629 \u0639\u0627\u0644\u064a\u0629 \u0639\u0644\u0649 \u0627\u0631\u062a\u0641\u0627\u0639 \u0645\u0646\u062e\u0641\u0636 \u0641\u0648\u0642 \u0645\u062f\u0631\u062c \u0627\u0644\u0645\u0637\u0627\u0631<\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><\/div><div class=\"et_pb_section_5 et_pb_section et_section_regular et_block_section\"><div class=\"et_pb_row_7 et_pb_row et_block_row\"><div class=\"et_pb_column_12 et_pb_column et_pb_column_1_2 et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_7 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h2>\u0645\u0648\u0642\u0639<\/h2>\n<\/div><\/div><\/div><div class=\"et_pb_column_13 et_pb_column et_pb_column_1_2 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_8 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h2>\u0627\u0644\u062a\u0648\u0627\u0641\u0631 \u0648\u0627\u0644\u062d\u062c\u0632<\/h2>\n<\/div><\/div><\/div><\/div><div class=\"et_pb_row_8 et_pb_row et_block_row\"><div class=\"et_pb_column_14 et_pb_column et_pb_column_3_5 et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_9 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h2>\u0645\u0648\u0642\u0639<\/h2>\n<\/div><\/div><div class=\"et_pb_image_3 et_pb_image et_pb_module et_block_module\"><a href=\"https:\/\/www.google.ch\/maps\/place\/Flughafen+Slia%C4%8D\/@49.7264491,9.2731644,5.66z\/data=!4m6!3m5!1s0x47153922a91c9e19:0xe2088d4b2734d2e3!8m2!3d48.6407144!4d19.1405952!16s%2Fm%2F02687p9?hl=en&#038;entry=ttu\" target=\"_blank\"><span class=\"et_pb_image_wrap\"><img data-opt-id=1147078199  data-opt-src=\"https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:auto\/h:auto\/q:96\/f:best\/https:\/\/migflug.com\/wp-content\/uploads\/2023\/11\/map-l29-slovakia-1.jpg\"  decoding=\"async\" src=\"data:image/svg+xml,%3Csvg%20viewBox%3D%220%200%20100%%20100%%22%20width%3D%22100%%22%20height%3D%22100%%22%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%3E%3Crect%20width%3D%22100%%22%20height%3D%22100%%22%20fill%3D%22transparent%22%2F%3E%3C%2Fsvg%3E\" width=\"1270\" height=\"1182\" old-srcset=\"https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:1160\/h:1080\/q:96\/f:best\/https:\/\/migflug.com\/wp-content\/uploads\/2023\/11\/map-l29-slovakia-1.jpg 1270w, https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:980\/h:912\/q:96\/f:best\/https:\/\/migflug.com\/wp-content\/uploads\/2023\/11\/map-l29-slovakia-1.jpg 980w, https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:480\/h:447\/q:96\/f:best\/https:\/\/migflug.com\/wp-content\/uploads\/2023\/11\/map-l29-slovakia-1.jpg 480w, https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:1160\/h:1080\/q:96\/f:best\/dpr:2\/https:\/\/migflug.com\/wp-content\/uploads\/2023\/11\/map-l29-slovakia-1.jpg 2x\" class=\"wp-image-5979\" title=\"\u062e\u0631\u064a\u0637\u0629 \u0633\u0644\u0648\u0641\u0627\u0643\u064a\u0627 l29\" \/><\/span><\/a><\/div><div class=\"et_pb_image_4 et_pb_image et_pb_module et_block_module\"><a href=\"https:\/\/www.google.ch\/maps\/place\/Flughafen+Slia%C4%8D\/@49.7264491,9.2731644,5.66z\/data=!4m6!3m5!1s0x47153922a91c9e19:0xe2088d4b2734d2e3!8m2!3d48.6407144!4d19.1405952!16s%2Fm%2F02687p9?hl=en&#038;entry=ttu\" target=\"_blank\"><span class=\"et_pb_image_wrap\"><img data-opt-id=1147078199  data-opt-src=\"https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:auto\/h:auto\/q:96\/f:best\/https:\/\/migflug.com\/wp-content\/uploads\/2023\/11\/map-l29-slovakia-1.jpg\"  decoding=\"async\" src=\"data:image/svg+xml,%3Csvg%20viewBox%3D%220%200%20100%%20100%%22%20width%3D%22100%%22%20height%3D%22100%%22%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%3E%3Crect%20width%3D%22100%%22%20height%3D%22100%%22%20fill%3D%22transparent%22%2F%3E%3C%2Fsvg%3E\" width=\"1270\" height=\"1182\" old-srcset=\"https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:1160\/h:1080\/q:96\/f:best\/https:\/\/migflug.com\/wp-content\/uploads\/2023\/11\/map-l29-slovakia-1.jpg 1270w, https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:980\/h:912\/q:96\/f:best\/https:\/\/migflug.com\/wp-content\/uploads\/2023\/11\/map-l29-slovakia-1.jpg 980w, https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:480\/h:447\/q:96\/f:best\/https:\/\/migflug.com\/wp-content\/uploads\/2023\/11\/map-l29-slovakia-1.jpg 480w, https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:1160\/h:1080\/q:96\/f:best\/dpr:2\/https:\/\/migflug.com\/wp-content\/uploads\/2023\/11\/map-l29-slovakia-1.jpg 2x\" class=\"wp-image-5979\" title=\"\u062e\u0631\u064a\u0637\u0629 \u0633\u0644\u0648\u0641\u0627\u0643\u064a\u0627 l29\" \/><\/span><\/a><\/div><\/div><div class=\"et_pb_column_15 et_pb_column et_pb_column_2_5 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_10 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h2>\u0627\u0644\u062a\u0648\u0627\u0641\u0631 \u0648\u0627\u0644\u062d\u062c\u0632<\/h2>\n<\/div><\/div><\/div><\/div><\/div><div class=\"et_pb_section_6 et_pb_section et_section_regular et_block_section\"><div class=\"et_pb_row_9 et_pb_row et_block_row\"><div class=\"et_pb_column_16 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_11 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h2>\u0634\u0647\u0627\u062f\u0627\u062a \u0627\u0644\u0639\u0645\u0644\u0627\u0621 - \u0645\u0627 \u064a\u0642\u0648\u0644\u0647 \u0639\u0645\u0644\u0627\u0624\u0646\u0627<\/h2>\n<\/div><\/div><\/div><\/div><\/div><div class=\"et_pb_section_7 et_pb_section et_section_regular et_block_section section_has_divider et_pb_top_divider et_pb_bottom_divider\"><div class=\"et_pb_top_inside_divider et-no-transition\"><\/div><div class=\"et_pb_row_10 et_pb_row et_block_row\"><div class=\"et_pb_column_17 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_blurb_0 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_top et_pb_module et_block_module\" id=\"btn-bottom-info\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><a href=\"https:\/\/migflug.com\/de\/flug-schenken\/\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\ue015<\/span><\/span><\/a><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\"><a href=\"https:\/\/migflug.com\/de\/flug-schenken\/\">\u0627\u062d\u062c\u0632 \u0631\u062d\u0644\u0629 \u0637\u064a\u0631\u0627\u0646 \u062e\u0627\u0635\u0629<\/a><\/h4><div class=\"et_pb_blurb_description\"><p>\u0647\u0644 \u0623\u0646\u062a \u0645\u0633\u062a\u0639\u062f \u0644\u0645\u063a\u0627\u0645\u0631\u0629 \u0637\u064a\u0631\u0627\u0646 \u0645\u0642\u0627\u062a\u0644\u0629 \u0633\u0644\u0648\u0641\u0627\u0643\u064a\u0629 \u0628\u0623\u0633\u0639\u0627\u0631 \u0645\u0639\u0642\u0648\u0644\u0629\u061f \u0627\u0645\u0644\u0623 \u0646\u0645\u0648\u0630\u062c \u0627\u0644\u062d\u062c\u0632 \u0648\u0633\u0646\u062a\u0648\u0627\u0635\u0644 \u0645\u0639\u0643 \u0642\u0631\u064a\u0628\u0627\u064b!<\/p>\n<\/div><\/div><\/div><\/div><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_4_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_4 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/book.migflug.com\/?location=SK-SLIAC-L29\" id=\"btn-bottom-book\">\u0627\u062d\u062c\u0632 \u0631\u062d\u0644\u062a\u0643<\/a><\/div><\/div><div class=\"et_pb_column_18 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_blurb_1 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_top et_pb_module et_block_module\" id=\"btn-bottom-info\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><a href=\"https:\/\/migflug.com\/ar\/%d8%b4%d8%b1%d8%a7%d8%a1-%d9%82%d8%b3%d9%8a%d9%85%d8%a9-%d9%87%d8%af%d9%8a%d8%a9-%d8%b7%d9%8a%d8%b1%d8%a7%d9%86\/\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\ue073<\/span><\/span><\/a><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\"><a href=\"https:\/\/migflug.com\/ar\/%d8%b4%d8%b1%d8%a7%d8%a1-%d9%82%d8%b3%d9%8a%d9%85%d8%a9-%d9%87%d8%af%d9%8a%d8%a9-%d8%b7%d9%8a%d8%b1%d8%a7%d9%86\/\">\u0642\u0633\u064a\u0645\u0629 \u0647\u062f\u064a\u0629 \u0631\u062d\u0644\u0629 \u0637\u064a\u0631\u0627\u0646<\/a><\/h4><div class=\"et_pb_blurb_description\"><p>\u0623\u0641\u0636\u0644 \u0647\u062f\u064a\u0629 \u0644\u0623\u0641\u0636\u0644 \u0634\u062e\u0635 \u0641\u064a \u0647\u0630\u0627 \u0627\u0644\u0639\u0627\u0644\u0645\u061f \u0627\u0644\u062a\u062d\u0644\u064a\u0642 \u0628\u0637\u0627\u0626\u0631\u0629 \u0645\u0642\u0627\u062a\u0644\u0629 \u062d\u0642\u064a\u0642\u064a\u0629 \u0641\u064a \u0633\u0644\u064a\u0627\u0643\u060c \u0633\u0644\u0648\u0641\u0627\u0643\u064a\u0627!<\/p>\n<\/div><\/div><\/div><\/div><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_5_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_5 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/book.migflug.com\/?location=SK-SLIAC-L29&#038;isgift=ADDON-GIFT\" id=\"btn-bottom-gift\">\u0627\u0634\u062a\u0631\u0650 \u0642\u0633\u064a\u0645\u0629 \u0647\u062f\u064a\u0629<\/a><\/div><\/div><div class=\"et_pb_column_19 et_pb_column et_pb_column_1_3 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_blurb_2 et_pb_blurb et_pb_bg_layout_light et_pb_blurb_position_top et_pb_module et_block_module\" id=\"btn-bottom-info\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><a href=\"https:\/\/migflug.com\/de\/flug-buchen\/\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">w<\/span><\/span><\/a><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\"><a href=\"https:\/\/migflug.com\/de\/flug-buchen\/\">\u0627\u062a\u0635\u0644 \u0628\u0646\u0627<\/a><\/h4><div class=\"et_pb_blurb_description\"><p>\u0647\u0644 \u062a\u0631\u063a\u0628\u0648\u0646 \u0628\u0645\u0639\u0631\u0641\u0629 \u0627\u0644\u0645\u0632\u064a\u062f \u0639\u0646 \u0631\u062d\u0644\u0627\u062a\u0646\u0627 \u0627\u0644\u062c\u0648\u064a\u0629 \u0627\u0644\u062e\u0627\u0635\u0629\u060c \u0648\u0639\u0631\u0648\u0636 \u0627\u0644\u0645\u062c\u0645\u0648\u0639\u0627\u062a \u0648\u0627\u0644\u062d\u0648\u0627\u0641\u0632\u061f \u0644\u0627 \u062a\u062a\u0631\u062f\u062f\u0648\u0627 \u0641\u064a \u0627\u0644\u0627\u062a\u0635\u0627\u0644 \u0628\u0646\u0627.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_6_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_6 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/migflug.com\/ar\/%d9%84%d9%84%d9%85%d8%b2%d9%8a%d8%af-%d9%85%d9%86-%d8%a7%d9%84%d9%85%d8%b9%d9%84%d9%88%d9%85%d8%a7%d8%aa\/?params=displaylocation&#038;location=SK-SLIAC\" id=\"btn-bottom-info\">\u0637\u0644\u0628 \u0645\u0639\u0644\u0648\u0645\u0627\u062a<\/a><\/div><\/div><\/div><div class=\"et_pb_bottom_inside_divider et-no-transition\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":52,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"editor_notices":[],"footnotes":""},"class_list":["post-257","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L-29 Dolphin Jet Fighter in Sliac, Slovakia | MiGFlug.com<\/title>\n<meta name=\"description\" content=\"Fly the robust Jet Trainer L-29 dolphin located in Sliac (Slovakia). No previous knowledge required. Book now and book online.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/migflug.com\/ar\/\u0623\u0633\u0639\u0627\u0631-\u0627\u0644\u0631\u062d\u0644\u0627\u062a-\u0627\u0644\u062c\u0648\u064a\u0629\/l-29-\u062f\u0644\u0641\u064a\u0646-\u0633\u0644\u0648\u0641\u0627\u0643\u064a\u0627\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L-29 Dolphin Jet Fighter in Sliac, Slovakia | MiGFlug.com\" \/>\n<meta property=\"og:description\" content=\"Fly the robust Jet Trainer L-29 dolphin located in Sliac (Slovakia). No previous knowledge required. Book now and book online.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/migflug.com\/ar\/\u0623\u0633\u0639\u0627\u0631-\u0627\u0644\u0631\u062d\u0644\u0627\u062a-\u0627\u0644\u062c\u0648\u064a\u0629\/l-29-\u062f\u0644\u0641\u064a\u0646-\u0633\u0644\u0648\u0641\u0627\u0643\u064a\u0627\/\" \/>\n<meta property=\"og:site_name\" content=\"MiGFlug\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MiGFlug\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-22T21:16:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:auto\/h:auto\/q:96\/f:best\/https:\/\/migflug.com\/wp-content\/uploads\/2026\/06\/migflug-share-1200x630-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@migflug\" \/>\n<meta name=\"twitter:label1\" content=\"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 \u062f\u0642\u0627\u0626\u0642\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/migflug.com\\\/flights-prices\\\/l-29-delfin-slovakia\\\/\",\"url\":\"https:\\\/\\\/migflug.com\\\/flights-prices\\\/l-29-delfin-slovakia\\\/\",\"name\":\"L-29 Dolphin Jet Fighter in Sliac, Slovakia | MiGFlug.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/migflug.com\\\/#website\"},\"datePublished\":\"2017-06-08T17:10:33+00:00\",\"dateModified\":\"2026-06-22T21:16:08+00:00\",\"description\":\"Fly the robust Jet Trainer L-29 dolphin located in Sliac (Slovakia). No previous knowledge required. Book now and book online.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/migflug.com\\\/flights-prices\\\/l-29-delfin-slovakia\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/migflug.com\\\/flights-prices\\\/l-29-delfin-slovakia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/migflug.com\\\/flights-prices\\\/l-29-delfin-slovakia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/migflug.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Flights &amp; Prices\",\"item\":\"https:\\\/\\\/migflug.com\\\/flights-prices\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"L-29 Delfin in Slovakia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/migflug.com\\\/#website\",\"url\":\"https:\\\/\\\/migflug.com\\\/\",\"name\":\"MiGFlug\",\"description\":\"Fly a Jet Fighter Yourself\",\"publisher\":{\"@id\":\"https:\\\/\\\/migflug.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/migflug.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/migflug.com\\\/#organization\",\"name\":\"MiGFlug GmbH\",\"url\":\"https:\\\/\\\/migflug.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/migflug.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\/\\/migflug.com\\/wp-content\\/uploads\\/2018\\/10\\/logo-migflug-blue.png\",\"contentUrl\":\"https:\\/\\/migflug.com\\/wp-content\\/uploads\\/2018\\/10\\/logo-migflug-blue.png\",\"width\":200,\"height\":100,\"caption\":\"MiGFlug GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/migflug.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MiGFlug\\\/\",\"https:\\\/\\\/x.com\\\/migflug\",\"https:\\\/\\\/www.instagram.com\\\/migflug\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/MiGFlug\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/migflug.com\\\/\",\"https:\\\/\\\/www.pinterest.ch\\\/migflug\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0637\u0627\u0626\u0631\u0629 \u0645\u0642\u0627\u062a\u0644\u0629 \u0645\u0646 \u0637\u0631\u0627\u0632 L-29 \u062f\u0648\u0644\u0641\u064a\u0646 \u0641\u064a \u0633\u0644\u064a\u0627\u0643\u060c \u0633\u0644\u0648\u0641\u0627\u0643\u064a\u0627 | MiGFlug.com","description":"\u0627\u0633\u062a\u0645\u062a\u0639 \u0628\u062a\u062c\u0631\u0628\u0629 \u0637\u064a\u0631\u0627\u0646 \u0645\u0645\u064a\u0632\u0629 \u0639\u0644\u0649 \u0645\u062a\u0646 \u0637\u0627\u0626\u0631\u0629 \u0627\u0644\u062a\u062f\u0631\u064a\u0628 \u0627\u0644\u0646\u0641\u0627\u062b\u0629 \u0627\u0644\u0642\u0648\u064a\u0629 L-29 \u062f\u0648\u0644\u0641\u064a\u0646\u060c \u0627\u0644\u0645\u062a\u0648\u0641\u0631\u0629 \u0641\u064a \u0633\u0644\u064a\u0627\u0643 (\u0633\u0644\u0648\u0641\u0627\u0643\u064a\u0627). \u0644\u0627 \u064a\u0634\u062a\u0631\u0637 \u0623\u064a \u062e\u0628\u0631\u0629 \u0645\u0633\u0628\u0642\u0629. \u0627\u062d\u062c\u0632 \u0627\u0644\u0622\u0646 \u0639\u0628\u0631 \u0627\u0644\u0625\u0646\u062a\u0631\u0646\u062a.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/migflug.com\/ar\/\u0623\u0633\u0639\u0627\u0631-\u0627\u0644\u0631\u062d\u0644\u0627\u062a-\u0627\u0644\u062c\u0648\u064a\u0629\/l-29-\u062f\u0644\u0641\u064a\u0646-\u0633\u0644\u0648\u0641\u0627\u0643\u064a\u0627\/","og_locale":"ar_AR","og_type":"article","og_title":"L-29 Dolphin Jet Fighter in Sliac, Slovakia | MiGFlug.com","og_description":"Fly the robust Jet Trainer L-29 dolphin located in Sliac (Slovakia). No previous knowledge required. Book now and book online.","og_url":"https:\/\/migflug.com\/ar\/\u0623\u0633\u0639\u0627\u0631-\u0627\u0644\u0631\u062d\u0644\u0627\u062a-\u0627\u0644\u062c\u0648\u064a\u0629\/l-29-\u062f\u0644\u0641\u064a\u0646-\u0633\u0644\u0648\u0641\u0627\u0643\u064a\u0627\/","og_site_name":"MiGFlug","article_publisher":"https:\/\/www.facebook.com\/MiGFlug\/","article_modified_time":"2026-06-22T21:16:08+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:auto\/h:auto\/q:96\/f:best\/https:\/\/migflug.com\/wp-content\/uploads\/2026\/06\/migflug-share-1200x630-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@migflug","twitter_misc":{"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631":"5 \u062f\u0642\u0627\u0626\u0642"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/migflug.com\/flights-prices\/l-29-delfin-slovakia\/","url":"https:\/\/migflug.com\/flights-prices\/l-29-delfin-slovakia\/","name":"\u0637\u0627\u0626\u0631\u0629 \u0645\u0642\u0627\u062a\u0644\u0629 \u0645\u0646 \u0637\u0631\u0627\u0632 L-29 \u062f\u0648\u0644\u0641\u064a\u0646 \u0641\u064a \u0633\u0644\u064a\u0627\u0643\u060c \u0633\u0644\u0648\u0641\u0627\u0643\u064a\u0627 | MiGFlug.com","isPartOf":{"@id":"https:\/\/migflug.com\/#website"},"datePublished":"2017-06-08T17:10:33+00:00","dateModified":"2026-06-22T21:16:08+00:00","description":"\u0627\u0633\u062a\u0645\u062a\u0639 \u0628\u062a\u062c\u0631\u0628\u0629 \u0637\u064a\u0631\u0627\u0646 \u0645\u0645\u064a\u0632\u0629 \u0639\u0644\u0649 \u0645\u062a\u0646 \u0637\u0627\u0626\u0631\u0629 \u0627\u0644\u062a\u062f\u0631\u064a\u0628 \u0627\u0644\u0646\u0641\u0627\u062b\u0629 \u0627\u0644\u0642\u0648\u064a\u0629 L-29 \u062f\u0648\u0644\u0641\u064a\u0646\u060c \u0627\u0644\u0645\u062a\u0648\u0641\u0631\u0629 \u0641\u064a \u0633\u0644\u064a\u0627\u0643 (\u0633\u0644\u0648\u0641\u0627\u0643\u064a\u0627). \u0644\u0627 \u064a\u0634\u062a\u0631\u0637 \u0623\u064a \u062e\u0628\u0631\u0629 \u0645\u0633\u0628\u0642\u0629. \u0627\u062d\u062c\u0632 \u0627\u0644\u0622\u0646 \u0639\u0628\u0631 \u0627\u0644\u0625\u0646\u062a\u0631\u0646\u062a.","breadcrumb":{"@id":"https:\/\/migflug.com\/flights-prices\/l-29-delfin-slovakia\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/migflug.com\/flights-prices\/l-29-delfin-slovakia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/migflug.com\/flights-prices\/l-29-delfin-slovakia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/migflug.com\/"},{"@type":"ListItem","position":2,"name":"Flights &amp; Prices","item":"https:\/\/migflug.com\/flights-prices\/"},{"@type":"ListItem","position":3,"name":"L-29 Delfin in Slovakia"}]},{"@type":"WebSite","@id":"https:\/\/migflug.com\/#website","url":"https:\/\/migflug.com\/","name":"\u0645\u064a\u063a\u0641\u0644\u0648\u063a","description":"\u0642\u0645 \u0628\u0642\u064a\u0627\u062f\u0629 \u0637\u0627\u0626\u0631\u0629 \u0645\u0642\u0627\u062a\u0644\u0629 \u0646\u0641\u0627\u062b\u0629 \u0628\u0646\u0641\u0633\u0643","publisher":{"@id":"https:\/\/migflug.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/migflug.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/migflug.com\/#organization","name":"\u0634\u0631\u0643\u0629 MiGFlug GmbH","url":"https:\/\/migflug.com\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/migflug.com\/#\/schema\/logo\/image\/","url":"https:\/\/migflug.com\/wp-content\/uploads\/2018\/10\/logo-migflug-blue.png","contentUrl":"https:\/\/migflug.com\/wp-content\/uploads\/2018\/10\/logo-migflug-blue.png","width":200,"height":100,"caption":"MiGFlug GmbH"},"image":{"@id":"https:\/\/migflug.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MiGFlug\/","https:\/\/x.com\/migflug","https:\/\/www.instagram.com\/migflug\/","https:\/\/www.youtube.com\/user\/MiGFlug","https:\/\/www.linkedin.com\/company\/migflug.com\/","https:\/\/www.pinterest.ch\/migflug\/"]}]}},"_links":{"self":[{"href":"https:\/\/migflug.com\/ar\/wp-json\/wp\/v2\/pages\/257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/migflug.com\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/migflug.com\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/migflug.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/migflug.com\/ar\/wp-json\/wp\/v2\/comments?post=257"}],"version-history":[{"count":4,"href":"https:\/\/migflug.com\/ar\/wp-json\/wp\/v2\/pages\/257\/revisions"}],"predecessor-version":[{"id":15648,"href":"https:\/\/migflug.com\/ar\/wp-json\/wp\/v2\/pages\/257\/revisions\/15648"}],"up":[{"embeddable":true,"href":"https:\/\/migflug.com\/ar\/wp-json\/wp\/v2\/pages\/52"}],"wp:attachment":[{"href":"https:\/\/migflug.com\/ar\/wp-json\/wp\/v2\/media?parent=257"}],"curies":[{"name":"\u0648\u0648\u0631\u062f\u0628\u0631\u064a\u0633","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}