{"id":297,"date":"2017-06-09T10:47:22","date_gmt":"2017-06-09T08:47:22","guid":{"rendered":"http:\/\/migflug.com\/?page_id=297"},"modified":"2026-06-22T23:16:27","modified_gmt":"2026-06-22T21:16:27","slug":"mig-29-fulcrum-rusia","status":"publish","type":"page","link":"https:\/\/migflug.com\/es\/flights-prices\/mig-29-fulcrum-russia\/","title":{"rendered":"MiG-29 Fulcrum en Rusia"},"content":{"rendered":"<div class=\"et_pb_section_0 et_pb_section et_pb_fullwidth_section et_section_regular et_block_section\"><div class=\"et_pb_fullwidth_image_0 et_pb_fullwidth_image et_pb_module\"><img data-opt-id=1987952996  data-opt-src=\"https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:auto\/h:auto\/q:96\/f:best\/https:\/\/migflug.com\/de\/wp-content\/uploads\/sites\/2\/2017\/04\/mig-29-flight-russia-2.jpg\"  decoding=\"async\" src=\"data:image/svg+xml,%3Csvg%20viewBox%3D%220%200%20100%%20100%%22%20width%3D%22100%%22%20height%3D%22100%%22%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%3E%3Crect%20width%3D%22100%%22%20height%3D%22100%%22%20fill%3D%22transparent%22%2F%3E%3C%2Fsvg%3E\" alt=\"MiG-29, Rusia\" \/><\/div><div class=\"et_pb_fullwidth_image_1 et_pb_fullwidth_image et_pb_module\"><img data-opt-id=2009777647  data-opt-src=\"https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:auto\/h:auto\/q:96\/f:best\/https:\/\/migflug.com\/de\/wp-content\/uploads\/sites\/2\/2017\/01\/demo3-Screen-Shot-2014-09-09-at-16.jpg\"  decoding=\"async\" src=\"data:image/svg+xml,%3Csvg%20viewBox%3D%220%200%20100%%20100%%22%20width%3D%22100%%22%20height%3D%22100%%22%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%3E%3Crect%20width%3D%22100%%22%20height%3D%22100%%22%20fill%3D%22transparent%22%2F%3E%3C%2Fsvg%3E\" alt=\"MiG-29, Rusia\" \/><\/div><\/div><div class=\"et_pb_section_1 et_pb_section et_section_regular et_block_section\"><div class=\"et_pb_row_0 et_pb_row et_block_row\"><div class=\"et_pb_column_0 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_0 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h2>Vuelo en avi\u00f3n MiG-29 en Rusia: vuelos desde 12.500 \u20ac<\/h2>\n<p><span style=\"color: #8300e9;\"><strong>El vuelo del MiG-29 ya no est\u00e1 disponible<\/strong><\/span><\/p>\n<p class=\"main-text\">12.500 \u20ac por 25 min sin supers\u00f3nico<br \/>14.500 \u20ac por un vuelo supers\u00f3nico de 45 min<\/p>\n<\/div><\/div><\/div><\/div><div class=\"et_pb_row_1 et_pb_row et_pb_row_4col et_block_row et_block_row_4col\"><div class=\"et_pb_column_1 et_pb_column et_pb_column_1_4 et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_0_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_0 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/migflug.com\/de\/flug-infos-anfragen\/\">Solicitar informaci\u00f3n<\/a><\/div><\/div><div class=\"et_pb_column_2 et_pb_column et_pb_column_1_4 et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_1_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_1 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/migflug.com\/de\/flug-buchen\/\">Reserva un vuelo en avi\u00f3n de combate ahora<\/a><\/div><\/div><div class=\"et_pb_column_3 et_pb_column et_pb_column_1_4 et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_2_wrapper preset--module--divi-button--default_wrapper\"><a class=\"et_pb_button_2 et_pb_button et_pb_bg_layout_light et_pb_module et_block_module preset--module--divi-button--default\" href=\"https:\/\/migflug.com\/de\/flug-schenken\/\">Compre un certificado de regalo de vuelo<\/a><\/div><\/div><div class=\"et_pb_column_4 et_pb_column et_pb_column_1_4 et-last-child et_block_column et_pb_column_empty et_pb_css_mix_blend_mode_passthrough\"><\/div><\/div><\/div><div class=\"et_pb_section_2 et_pb_section et_section_regular et_block_section\"><div class=\"et_pb_row_2 et_pb_row et_block_row\"><div class=\"et_pb_column_5 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_1 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h1>Vuela el MiG-29 Fulcrum en Rusia<\/h1>\n<\/div><\/div><div class=\"et_pb_text_2 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><p class=\"bodytext\">Durante la Guerra Fr\u00eda, la <a href=\"https:\/\/migflug.com\/es\/proyecto\/mig-29\/\">MiG-29 Fulcrum<\/a> Fue la punta de lanza de la Fuerza A\u00e9rea Sovi\u00e9tica y era temido en Occidente por su excelente maniobrabilidad tanto a velocidades subs\u00f3nicas como supers\u00f3nicas. Ahora tiene la oportunidad de volar uno de estos modernos aviones de combate: le ofrecemos la posibilidad de volar un MiG-29 UB en Rusia. Para los aficionados a los cazas civiles, actualmente solo hay un lugar donde se puede experimentar legalmente el vuelo del MiG-29 Fulcrum: el aer\u00f3dromo SOKOL, cerca de la ciudad rusa de Nizhni N\u00f3vgorod. La ciudad forma parte del complejo militar-industrial ruso. Recientemente, este lugar se ha abierto al p\u00fablico sin autorizaci\u00f3n especial.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"et_pb_row_3 et_pb_row et_pb_gutters1 et_block_row et_pb_row_fullwidth\"><div class=\"et_pb_column_6 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_image_0 et_pb_image et_pb_image_sticky et_animated et_pb_module et_block_module\"><span class=\"et_pb_image_wrap\"><img data-opt-id=13771228  data-opt-src=\"https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:auto\/h:auto\/q:96\/f:best\/https:\/\/migflug.com\/de\/wp-content\/uploads\/sites\/2\/2017\/04\/mig-29-flight-russia-24.jpg\"  decoding=\"async\" src=\"data:image/svg+xml,%3Csvg%20viewBox%3D%220%200%20100%%20100%%22%20width%3D%22100%%22%20height%3D%22100%%22%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%3E%3Crect%20width%3D%22100%%22%20height%3D%22100%%22%20fill%3D%22transparent%22%2F%3E%3C%2Fsvg%3E\" alt=\"Hawker Hunter vuela en Suiza\" \/><\/span><\/div><\/div><div class=\"et_pb_column_7 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_image_1 et_pb_image et_pb_image_sticky et_animated et_pb_module et_block_module\"><span class=\"et_pb_image_wrap\"><img data-opt-id=484970106  data-opt-src=\"https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:auto\/h:auto\/q:96\/f:best\/https:\/\/migflug.com\/de\/wp-content\/uploads\/sites\/2\/2017\/04\/mig-29-flight-russia-21.jpg\"  decoding=\"async\" src=\"data:image/svg+xml,%3Csvg%20viewBox%3D%220%200%20100%%20100%%22%20width%3D%22100%%22%20height%3D%22100%%22%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%3E%3Crect%20width%3D%22100%%22%20height%3D%22100%%22%20fill%3D%22transparent%22%2F%3E%3C%2Fsvg%3E\" alt=\"Hawker Hunter vuela en Suiza\" \/><\/span><\/div><\/div><div class=\"et_pb_column_8 et_pb_column et_pb_column_1_3 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_image_2 et_pb_image et_pb_image_sticky et_animated et_pb_module et_block_module\"><span class=\"et_pb_image_wrap\"><img data-opt-id=1213815964  data-opt-src=\"https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:auto\/h:auto\/q:96\/f:best\/https:\/\/migflug.com\/de\/wp-content\/uploads\/sites\/2\/2017\/04\/mig-29-flight-russia-22.jpg\"  decoding=\"async\" src=\"data:image/svg+xml,%3Csvg%20viewBox%3D%220%200%20100%%20100%%22%20width%3D%22100%%22%20height%3D%22100%%22%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%3E%3Crect%20width%3D%22100%%22%20height%3D%22100%%22%20fill%3D%22transparent%22%2F%3E%3C%2Fsvg%3E\" alt=\"Hawker Hunter vuela en Suiza\" \/><\/span><\/div><\/div><\/div><\/div><div class=\"et_pb_section_3 et_pb_section et_section_regular et_block_section\"><div class=\"et_pb_row_4 et_pb_row et_block_row\"><div class=\"et_pb_column_9 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_3 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h2>Volar un MiG-29 Fulcrum: potencia bruta y altitud extrema<\/h2>\n<p class=\"bodytext\">Supervisado por nuestros experimentados pilotos de prueba, estar\u00e1 expuesto a la fuerza G de las dos poderosas turbinas del MiG-29. Se ejercer\u00e1 una fuerza de hasta 9 G sobre su cuerpo. Su cuerpo ser\u00e1 presionado contra el asiento mientras realiza maniobras especiales con el piloto, como giros, bucles, giros Immelmann y deslizamientos de cola. Sin embargo, estas maniobras, inspiradas en operaciones de combate reales, son solo el comienzo. Despu\u00e9s de un tiempo en el aire llega el gran momento culminante: \u00a1el piloto le entrega los controles para que vuele el MiG-29 Fulcrum completamente solo! Una cima totalmente diferente, literalmente: el vuelo al &quot;Borde del Espacio&quot;. Con un <a href=\"https:\/\/migflug.com\/es\/proyecto\/mig-29\/\">MiG-29 Fulcrum<\/a> Podr\u00e1s acercarte al espacio como nunca antes. El avi\u00f3n de combate te catapulta hasta los 22 km sobre el nivel del mar (17 km garantizados). A esta altura, la curvatura de la Tierra es visible y podr\u00e1s apreciar la inmensidad del espacio en toda su magnitud.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"et_pb_row_5 et_pb_row et_block_row\"><div class=\"et_pb_column_10 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_video_0 et_pb_video et_pb_module et_block_module\"><div class=\"et_pb_video_box\"><iframe hcb-fetch-image-from=\"https:\/\/youtu.be\/nv4USlmV1PQ\" title=\"El impresionante vuelo supers\u00f3nico Edge of Space con Pauline Nordin\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/nv4USlmV1PQ?feature=oembed&amp;controls=1\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div><\/div><\/div><\/div><\/div><div class=\"et_pb_section_4 et_pb_section et_section_regular et_block_section\"><div class=\"et_pb_row_6 et_pb_row et_block_row\"><div class=\"et_pb_column_11 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_divider_0 et_pb_divider_hidden et_pb_space et_pb_divider_position_top et_pb_module\"><div class=\"et_pb_divider_internal\"><\/div><\/div><div class=\"et_pb_text_4 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h2>Programa de vuelo del MiG-29 Fulcrum: \u00a1Pilota t\u00fa mismo!<\/h2>\n<p>No esperes un vuelo de patrulla aburrido con el <a href=\"https:\/\/migflug.com\/es\/proyecto\/mig-29\/\">MiG-29 Fulcrum<\/a>En cambio, te espera la acci\u00f3n. Pilotar\u00e1s el avi\u00f3n supers\u00f3nico MiG-29 Fulcrum y realizar\u00e1s maniobras audaces bajo las instrucciones del piloto. Hay tres programas de vuelo est\u00e1ndar para el MiG-29 Fulcrum, adem\u00e1s de un programa de entrenamiento para vuelos espaciales suborbitales:<\/p>\n<ul>\n<li>Acrobacias a\u00e9reas de 25 minutos con el MiG-29 Fulcrum sin vuelo supers\u00f3nico<\/li>\n<li>45 minutos de acrobacias a\u00e9reas superiores del MiG-29 Fulcrum, incluido vuelo supers\u00f3nico<\/li>\n<\/ul>\n<p class=\"bodytext\">El programa de vuelo comprende lo siguiente:<\/p>\n<ul>\n<li>Rompiendo la barrera del sonido<\/li>\n<li>Rollos<\/li>\n<li>Giro de Immelmann<\/li>\n<li>Bucles<\/li>\n<li>Split-s<\/li>\n<li>Ascenso y aceleraci\u00f3n en vertical<\/li>\n<li>Inmersiones y inmersiones verticales<\/li>\n<li>Curvas pronunciadas<\/li>\n<li>Deslizamiento de cola<\/li>\n<\/ul>\n<\/div><\/div><div class=\"et_pb_divider_1 et_pb_divider_hidden et_pb_space et_pb_divider_position_top et_pb_module\"><div class=\"et_pb_divider_internal\"><\/div><\/div><div class=\"et_pb_text_5 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h2>El d\u00eda de tu vuelo del MiG-29 en Rusia<\/h2>\n<p class=\"bodytext\">En el d\u00eda de tu <a href=\"https:\/\/migflug.com\/es\/proyecto\/mig-29\/\">MiG-29 Fulcrum<\/a> Para su vuelo, nuestro traductor y su conductor lo recoger\u00e1n en el vest\u00edbulo de su hotel aproximadamente a las 9 de la ma\u00f1ana. Tras un breve trayecto por Nizhny Novgorod, llegar\u00e1 a la entrada del aer\u00f3dromo de SOKOL. El personal de seguridad verificar\u00e1 su identificaci\u00f3n y autorizaci\u00f3n de acceso. A continuaci\u00f3n, su viaje continuar\u00e1 en un veh\u00edculo proporcionado por SOKOL, ya que solo los veh\u00edculos de la base a\u00e9rea pueden circular dentro del \u00e1rea militar. El piloto lo estar\u00e1 esperando en un edificio administrativo. En una sala de reuniones, podr\u00e1 conversar sobre su programa de vuelo con el piloto, quien intentar\u00e1 satisfacer la mayor cantidad posible de sus deseos.<\/p>\n<p class=\"bodytext\">Ahora lo llevan ante un t\u00e9cnico m\u00e9dico, quien le tomar\u00e1 el pulso y le realizar\u00e1 m\u00e1s ex\u00e1menes m\u00e9dicos. Luego lo llevan al vestuario, donde le entregan botas, guantes, un casco y un traje de vuelo. Tan pronto como todo le quede bien, su piloto lo guiar\u00e1 a la plataforma. All\u00ed lo espera &quot;su&quot; MiG-29 Fulcrum, que est\u00e1 siendo preparado por el personal de tierra. El piloto lo lleva a la aeronave y le explica los sistemas de doble redundancia. Despu\u00e9s de un recorrido extenso y un examen detallado de la aeronave,\u00a0<a href=\"https:\/\/migflug.com\/es\/proyecto\/mig-29\/\">MiG-29 Fulcrum<\/a> Subes por la escalera para entrar en la cabina. El piloto te explica la cabina una vez m\u00e1s, especialmente el telescopio, \u00a1que tendr\u00e1s que retraer t\u00fa mismo antes del despegue!<\/p>\n<p class=\"bodytext\">Una vez respondidas todas sus preguntas, su vuelo est\u00e1 a punto de comenzar. Seg\u00fan el programa de vuelo, despegar\u00e1 con postcombusti\u00f3n para un vuelo de entre 30 y 60 minutos. Una vez en el aire, experimentar\u00e1 espectaculares pasadas a baja altura a velocidades casi supers\u00f3nicas, a tan solo unos metros de la base a\u00e9rea. Maniobras como rizos, giros Immelmann, deslizamientos de cola y la maniobra especial &quot;martillo&quot; lo llevar\u00e1n al l\u00edmite de sus capacidades. \u00a1El MiG-29 incluso puede acelerar en posici\u00f3n vertical!<\/p>\n<p class=\"bodytext\">Tras aterrizar con el paraca\u00eddas de frenado, tendr\u00e1 la oportunidad de tomarse una foto de recuerdo con el piloto. Despu\u00e9s de un refrigerio, nuestro experimentado equipo lo acompa\u00f1ar\u00e1 de regreso a la base y luego lo llevar\u00e1 al hotel. Para terminar este d\u00eda inolvidable, le recomendamos encarecidamente brindar con un vaso de vodka.<\/p>\n<\/div><\/div><\/div><\/div><div class=\"et_pb_row_7 et_pb_row et_block_row\"><div class=\"et_pb_column_12 et_pb_column et_pb_column_1_2 et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_6 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h2>Standort<\/h2>\n<\/div><\/div><\/div><div class=\"et_pb_column_13 et_pb_column et_pb_column_1_2 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_7 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h2>Impresiones<\/h2>\n<\/div><\/div><\/div><\/div><div class=\"et_pb_row_8 et_pb_row et_block_row\"><div class=\"et_pb_column_14 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_8 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h2>Un vuelo en un MiG-29 Fulcrum - Todo Incluido<\/h2>\n<p class=\"bodytext\">Con un <a href=\"https:\/\/migflug.com\/es\/proyecto\/mig-29\/\">MiG-29 Fulcrum<\/a> Al volar con MiGFlug recibir\u00e1s mucho m\u00e1s que un simple vuelo en un moderno y legendario avi\u00f3n de combate:<\/p>\n<ul>\n<li>Traslado en limusina desde el hotel hasta el aer\u00f3dromo.<\/li>\n<li>Chequeo m\u00e9dico antes del vuelo<\/li>\n<li>Recorrido por la aeronave<\/li>\n<li>Transporte dentro de la enorme base a\u00e9rea<\/li>\n<li>Los hoteles y vuelos a Rusia se reservan para usted mediante <a href=\"https:\/\/migflug.com\/es\/sobre-nosotros\/\">MiGFlug<\/a>\u00a0a trav\u00e9s de nuestro socio oficial ISC IntelService, una de las mayores agencias de viajes receptivas de Rusia.<\/li>\n<li>Certificado de su vuelo<\/li>\n<li>Opcional: Reportaje en v\u00eddeo y fotos, incluyendo una web de recuerdo personalizada.<\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><\/div><div class=\"et_pb_section_5 et_pb_section et_section_regular et_block_section\"><div class=\"et_pb_row_9 et_pb_row et_block_row\"><div class=\"et_pb_column_15 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_9 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h2>Testimonios: Lo que dicen nuestros clientes<\/h2>\n<\/div><\/div><\/div><\/div><\/div><div class=\"et_pb_section_6 et_pb_section et_section_regular et_block_section\"><div class=\"et_pb_row_10 et_pb_row et_block_row\"><div class=\"et_pb_column_16 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\"><div class=\"et_pb_text_10 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module\"><div class=\"et_pb_text_inner\"><h2>El golpe tras el golpe: Vive Rusia<\/h2>\n<p class=\"bodytext\">En lo alto del cielo, te espera una aventura inolvidable. De vuelta en tierra firme, la Madre Rusia te aguarda con su rica historia y sus diversos lugares de inter\u00e9s. Visita la vibrante y cosmopolita ciudad de Mosc\u00fa, con sus restaurantes, tiendas, bares y discotecas. Sin duda, saciar\u00e1s tu sed de cultura y la cordial hospitalidad de sus habitantes te permitir\u00e1 entablar interesantes conversaciones.<\/p>\n<h2><\/h2>\n<\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":52,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"editor_notices":[],"footnotes":""},"class_list":["post-297","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Become a MiG-29 Fulcrum jet pilot in Russia for one day | MiGFlug.com<\/title>\n<meta name=\"description\" content=\"Fly the MiG-29 Fulcrum jet fighter in Nizhny Novgorod (Russia). No previous knowledge required. Book now and book online.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/migflug.com\/es\/precios-de-vuelos\/mig-29-fulcrum-rusia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Become a MiG-29 Fulcrum jet pilot in Russia for one day | MiGFlug.com\" \/>\n<meta property=\"og:description\" content=\"Fly the MiG-29 Fulcrum jet fighter in Nizhny Novgorod (Russia). No previous knowledge required. Book now and book online.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/migflug.com\/es\/precios-de-vuelos\/mig-29-fulcrum-rusia\/\" \/>\n<meta property=\"og:site_name\" content=\"MiGFlug\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MiGFlug\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-22T21:16:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:auto\/h:auto\/q:96\/f:best\/https:\/\/migflug.com\/wp-content\/uploads\/2026\/06\/migflug-share-1200x630-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@migflug\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/migflug.com\\\/flights-prices\\\/mig-29-fulcrum-russia\\\/\",\"url\":\"https:\\\/\\\/migflug.com\\\/flights-prices\\\/mig-29-fulcrum-russia\\\/\",\"name\":\"Become a MiG-29 Fulcrum jet pilot in Russia for one day | MiGFlug.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/migflug.com\\\/#website\"},\"datePublished\":\"2017-06-09T08:47:22+00:00\",\"dateModified\":\"2026-06-22T21:16:27+00:00\",\"description\":\"Fly the MiG-29 Fulcrum jet fighter in Nizhny Novgorod (Russia). No previous knowledge required. Book now and book online.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/migflug.com\\\/flights-prices\\\/mig-29-fulcrum-russia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/migflug.com\\\/flights-prices\\\/mig-29-fulcrum-russia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/migflug.com\\\/flights-prices\\\/mig-29-fulcrum-russia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/migflug.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Flights &amp; Prices\",\"item\":\"https:\\\/\\\/migflug.com\\\/flights-prices\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MiG-29 Fulcrum in Russia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/migflug.com\\\/#website\",\"url\":\"https:\\\/\\\/migflug.com\\\/\",\"name\":\"MiGFlug\",\"description\":\"Fly a Jet Fighter Yourself\",\"publisher\":{\"@id\":\"https:\\\/\\\/migflug.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/migflug.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/migflug.com\\\/#organization\",\"name\":\"MiGFlug GmbH\",\"url\":\"https:\\\/\\\/migflug.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/migflug.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\/\\/migflug.com\\/wp-content\\/uploads\\/2018\\/10\\/logo-migflug-blue.png\",\"contentUrl\":\"https:\\/\\/migflug.com\\/wp-content\\/uploads\\/2018\\/10\\/logo-migflug-blue.png\",\"width\":200,\"height\":100,\"caption\":\"MiGFlug GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/migflug.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/MiGFlug\\\/\",\"https:\\\/\\\/x.com\\\/migflug\",\"https:\\\/\\\/www.instagram.com\\\/migflug\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/MiGFlug\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/migflug.com\\\/\",\"https:\\\/\\\/www.pinterest.ch\\\/migflug\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Convi\u00e9rtete en piloto del avi\u00f3n MiG-29 Fulcrum en Rusia por un d\u00eda | MiGFlug.com","description":"Vuela el caza MiG-29 Fulcrum en Nizhni N\u00f3vgorod (Rusia). No se requieren conocimientos previos. Reserva ahora y en l\u00ednea.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/migflug.com\/es\/precios-de-vuelos\/mig-29-fulcrum-rusia\/","og_locale":"es_ES","og_type":"article","og_title":"Become a MiG-29 Fulcrum jet pilot in Russia for one day | MiGFlug.com","og_description":"Fly the MiG-29 Fulcrum jet fighter in Nizhny Novgorod (Russia). No previous knowledge required. Book now and book online.","og_url":"https:\/\/migflug.com\/es\/precios-de-vuelos\/mig-29-fulcrum-rusia\/","og_site_name":"MiGFlug","article_publisher":"https:\/\/www.facebook.com\/MiGFlug\/","article_modified_time":"2026-06-22T21:16:27+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/ml5psubhxdln.i.optimole.com\/cb:78--.b845\/w:auto\/h:auto\/q:96\/f:best\/https:\/\/migflug.com\/wp-content\/uploads\/2026\/06\/migflug-share-1200x630-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@migflug","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/migflug.com\/flights-prices\/mig-29-fulcrum-russia\/","url":"https:\/\/migflug.com\/flights-prices\/mig-29-fulcrum-russia\/","name":"Convi\u00e9rtete en piloto del avi\u00f3n MiG-29 Fulcrum en Rusia por un d\u00eda | MiGFlug.com","isPartOf":{"@id":"https:\/\/migflug.com\/#website"},"datePublished":"2017-06-09T08:47:22+00:00","dateModified":"2026-06-22T21:16:27+00:00","description":"Vuela el caza MiG-29 Fulcrum en Nizhni N\u00f3vgorod (Rusia). No se requieren conocimientos previos. Reserva ahora y en l\u00ednea.","breadcrumb":{"@id":"https:\/\/migflug.com\/flights-prices\/mig-29-fulcrum-russia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/migflug.com\/flights-prices\/mig-29-fulcrum-russia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/migflug.com\/flights-prices\/mig-29-fulcrum-russia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/migflug.com\/"},{"@type":"ListItem","position":2,"name":"Flights &amp; Prices","item":"https:\/\/migflug.com\/flights-prices\/"},{"@type":"ListItem","position":3,"name":"MiG-29 Fulcrum in Russia"}]},{"@type":"WebSite","@id":"https:\/\/migflug.com\/#website","url":"https:\/\/migflug.com\/","name":"MiGFlug","description":"Vuela t\u00fa mismo un avi\u00f3n de combate","publisher":{"@id":"https:\/\/migflug.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/migflug.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/migflug.com\/#organization","name":"MiGFlug GmbH","url":"https:\/\/migflug.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/migflug.com\/#\/schema\/logo\/image\/","url":"https:\/\/migflug.com\/wp-content\/uploads\/2018\/10\/logo-migflug-blue.png","contentUrl":"https:\/\/migflug.com\/wp-content\/uploads\/2018\/10\/logo-migflug-blue.png","width":200,"height":100,"caption":"MiGFlug GmbH"},"image":{"@id":"https:\/\/migflug.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/MiGFlug\/","https:\/\/x.com\/migflug","https:\/\/www.instagram.com\/migflug\/","https:\/\/www.youtube.com\/user\/MiGFlug","https:\/\/www.linkedin.com\/company\/migflug.com\/","https:\/\/www.pinterest.ch\/migflug\/"]}]}},"_links":{"self":[{"href":"https:\/\/migflug.com\/es\/wp-json\/wp\/v2\/pages\/297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/migflug.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/migflug.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/migflug.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/migflug.com\/es\/wp-json\/wp\/v2\/comments?post=297"}],"version-history":[{"count":5,"href":"https:\/\/migflug.com\/es\/wp-json\/wp\/v2\/pages\/297\/revisions"}],"predecessor-version":[{"id":15655,"href":"https:\/\/migflug.com\/es\/wp-json\/wp\/v2\/pages\/297\/revisions\/15655"}],"up":[{"embeddable":true,"href":"https:\/\/migflug.com\/es\/wp-json\/wp\/v2\/pages\/52"}],"wp:attachment":[{"href":"https:\/\/migflug.com\/es\/wp-json\/wp\/v2\/media?parent=297"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}